{"id":11691,"date":"2020-07-13T11:46:47","date_gmt":"2020-07-13T10:46:47","guid":{"rendered":"https:\/\/iacrianca.pt\/iac-on-media\/"},"modified":"2022-02-24T10:26:50","modified_gmt":"2022-02-24T10:26:50","slug":"iac-on-media","status":"publish","type":"page","link":"https:\/\/iacrianca.pt\/en\/news\/iac-on-media\/","title":{"rendered":"IAC on Media"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"11691\" class=\"elementor elementor-11691 elementor-3858\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-60ccef7b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"60ccef7b\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;shape_divider_bottom&quot;:&quot;mountains&quot;}\">\n\t\t\t\t\t<div class=\"elementor-shape elementor-shape-bottom\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" opacity=\"0.33\" d=\"M473,67.3c-203.9,88.3-263.1-34-320.3,0C66,119.1,0,59.7,0,59.7V0h1000v59.7 c0,0-62.1,26.1-94.9,29.3c-32.8,3.3-62.8-12.3-75.8-22.1C806,49.6,745.3,8.7,694.9,4.7S492.4,59,473,67.3z\"\/>\n\t<path class=\"elementor-shape-fill\" opacity=\"0.66\" d=\"M734,67.3c-45.5,0-77.2-23.2-129.1-39.1c-28.6-8.7-150.3-10.1-254,39.1 s-91.7-34.4-149.2,0C115.7,118.3,0,39.8,0,39.8V0h1000v36.5c0,0-28.2-18.5-92.1-18.5C810.2,18.1,775.7,67.3,734,67.3z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M766.1,28.9c-200-57.5-266,65.5-395.1,19.5C242,1.8,242,5.4,184.8,20.6C128,35.8,132.3,44.9,89.9,52.5C28.6,63.7,0,0,0,0 h1000c0,0-9.9,40.9-83.6,48.1S829.6,47,766.1,28.9z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c8c9b45\" data-id=\"c8c9b45\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1b38ef10 elementor-widget elementor-widget-heading\" data-id=\"1b38ef10\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">IAC on Media<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-859703a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"859703a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-40a2380\" data-id=\"40a2380\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2f359f8 elementor-widget elementor-widget-heading\" data-id=\"2f359f8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-large\">2022<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6b5548f elementor-tabs-view-vertical elementor-widget elementor-widget-tabs\" data-id=\"6b5548f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1121\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1121\" aria-expanded=\"false\">January<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1122\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1122\" aria-expanded=\"false\">February<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1123\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1123\" aria-expanded=\"false\">March<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1124\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"4\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1124\" aria-expanded=\"false\">April<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1125\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"5\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1125\" aria-expanded=\"false\">May<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1126\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"6\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1126\" aria-expanded=\"false\">June<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1127\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"7\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1127\" aria-expanded=\"false\">July<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1128\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"8\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1128\" aria-expanded=\"false\">August<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1129\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"9\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1129\" aria-expanded=\"false\">September<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-11210\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"10\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-11210\" aria-expanded=\"false\">October<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-11211\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"11\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-11211\" aria-expanded=\"false\">November<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-11212\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"12\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-11212\" aria-expanded=\"false\">December<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1121\" aria-expanded=\"false\">January<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1121\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1121\" tabindex=\"0\" hidden=\"false\"><p><span style=\"font-family: lato, 'helvetica neue', helvetica, arial, sans-serif; color: #000000;\"><strong>Respeitar os direitos das crian\u00e7as \u00e9 criar crian\u00e7as felizes<\/strong><\/span><br><a href=\"https:\/\/criancasatortoeadireitos.files.wordpress.com\/2022\/01\/familia-crista.pdf\" target=\"_blank\" rel=\"noopener\"><span style=\"font-family: noticia text, georgia, times new roman, serif;\">Fam\u00edlia Crist\u00e3 <\/span>(Jan. 2022), p. 30-36<\/a><span style=\"font-family: noticia text, georgia, times new roman, serif;\"> com declara\u00e7\u00f5es de Dulce Rocha.<\/span><\/p><p><span style=\"font-family: lato, 'helvetica neue', helvetica, arial, sans-serif; color: #000000;\"><strong>Telenovela da TVI alvo de processo na ERC<\/strong><\/span><br><span style=\"font-family: noticia text, georgia, times new roman, serif;\">Not\u00edcia do <a href=\"https:\/\/criancasatortoeadireitos.wordpress.com\/2022\/01\/14\/telenovela-da-tvi-alvo-de-processo-na-erc\/\" target=\"_blank\" rel=\"noopener\">Correio da Manh\u00e3<\/a> do dia 13 de janeiro de 2022. O IAC \u00e9 mencionado na not\u00edcia.<\/span><\/p><p><span style=\"font-family: lato, 'helvetica neue', helvetica, arial, sans-serif; color: #000000;\"><strong>&#8220;Quebrar o Sil\u00eancio. Um site e um telefone para denunciar 70 anos de abusos sexuais na Igreja Cat\u00f3lica<\/strong><\/span><br><span style=\"font-family: noticia text, georgia, times new roman, serif;\">Not\u00edcia do <a href=\"https:\/\/zap.aeiou.pt\/denunciar-abusos-sexuais-igreja-456427\" target=\"_blank\" rel=\"noopener\">ZAP aeiou<\/a> do dia 11 de janeiro de 2022. O IAC \u00e9 mencionado na not\u00edcia.<\/span><\/p><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1122\" aria-expanded=\"false\">February<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1122\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1122\" tabindex=\"0\" hidden=\"hidden\"><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1123\" aria-expanded=\"false\">March<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1123\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1123\" tabindex=\"0\" hidden=\"hidden\"><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"4\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1124\" aria-expanded=\"false\">April<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1124\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1124\" tabindex=\"0\" hidden=\"hidden\"><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"5\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1125\" aria-expanded=\"false\">May<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1125\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1125\" tabindex=\"0\" hidden=\"hidden\"><p> <\/p><p> <\/p><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"6\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1126\" aria-expanded=\"false\">June<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1126\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"6\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1126\" tabindex=\"0\" hidden=\"hidden\"><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"7\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1127\" aria-expanded=\"false\">July<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1127\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"7\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1127\" tabindex=\"0\" hidden=\"hidden\"><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"8\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1128\" aria-expanded=\"false\">August<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1128\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"8\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1128\" tabindex=\"0\" hidden=\"hidden\"><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"9\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1129\" aria-expanded=\"false\">September<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1129\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"9\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1129\" tabindex=\"0\" hidden=\"hidden\"><p><span style=\"font-family: noticia text, georgia, times new roman, serif;\">.<\/span><\/p><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"10\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-11210\" aria-expanded=\"false\">October<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-11210\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"10\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-11210\" tabindex=\"0\" hidden=\"hidden\"><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"11\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-11211\" aria-expanded=\"false\">November<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-11211\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"11\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-11211\" tabindex=\"0\" hidden=\"hidden\"><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"12\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-11212\" aria-expanded=\"false\">December<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-11212\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"12\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-11212\" tabindex=\"0\" hidden=\"hidden\"><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-81388a5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"81388a5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8fe53e5\" data-id=\"8fe53e5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8ca6af0 elementor-widget elementor-widget-heading\" data-id=\"8ca6af0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-large\">2021<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f6a557e elementor-tabs-view-vertical elementor-widget elementor-widget-tabs\" data-id=\"f6a557e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-2581\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-2581\" aria-expanded=\"false\">January<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-2582\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-2582\" aria-expanded=\"false\">February<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-2583\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-2583\" aria-expanded=\"false\">March<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-2584\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"4\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-2584\" aria-expanded=\"false\">April<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-2585\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"5\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-2585\" aria-expanded=\"false\">May<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-2586\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"6\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-2586\" aria-expanded=\"false\">June<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-2587\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"7\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-2587\" aria-expanded=\"false\">July<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-2588\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"8\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-2588\" aria-expanded=\"false\">August<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-2589\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"9\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-2589\" aria-expanded=\"false\">September<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-25810\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"10\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-25810\" aria-expanded=\"false\">October<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-25811\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"11\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-25811\" aria-expanded=\"false\">November<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-25812\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"12\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-25812\" aria-expanded=\"false\">December<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-2581\" aria-expanded=\"false\">January<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2581\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-2581\" tabindex=\"0\" hidden=\"false\"><p><strong>Nova legisla\u00e7\u00e3o de privacidade da UE compromete dete\u00e7\u00e3o de pornografia de menores online<\/strong><\/p><p>Not\u00edcia do <a href=\"https:\/\/criancasatortoeadireitos.wordpress.com\/2021\/01\/30\/nova-legislacao-de-privacidade-da-ue-compromete-deteccao-de-pornografia-de-menores-online\/\" target=\"_blank\" rel=\"noopener\">P\u00fablico<\/a> de 23 de janeiro. O IAC \u00e9 mencionado na not\u00edcia.<\/p><p><span style=\"font-family: lato, helvetica neue, helvetica, arial, sans-serif;\"><strong>Crian\u00e7as deprimidas : n\u00e3o \u00e9 uma contradi\u00e7\u00e3o<\/strong><\/span><br><span style=\"font-family: lato, helvetica neue, helvetica, arial, sans-serif;\">Not\u00edcia do <a href=\"https:\/\/iacrianca.pt\/wp-content\/uploads\/2021\/01\/PT-20210122-Expresso-REVISTA-E-1-1.pdf\" target=\"_blank\" rel=\"noopener\">Expresso<\/a> de 22 de janeiro com declara\u00e7\u00f5es de Manuel Coutinho<\/span><\/p><p><span style=\"font-family: lato, helvetica neue, helvetica, arial, sans-serif;\"><strong>Os conselhos dos especialistas para os pais que v\u00e3o deixar os filhos pela primeira vez sozinhos em casa<\/strong><\/span><br><span style=\"font-family: lato, helvetica neue, helvetica, arial, sans-serif;\">Not\u00edcia da <a href=\"https:\/\/criancasatortoeadireitos.wordpress.com\/2021\/01\/22\/os-conselhos-dos-especialistas-para-os-pais-que-vao-deixar-os-filhos-pela-primeira-vez-sozinhos-em-casa-noticia-com-declaracoes-de-maria-joao-cosme-do-iac\/\" target=\"_blank\" rel=\"noopener\">Vis\u00e3o<\/a> de 21 de janeiro com declara\u00e7\u00f5es de Maria Jo\u00e3o Cosme.<\/span><\/p><p><strong>Recorde de pedidos de ajuda \u00e0 SOS Crian\u00e7a no ano passado<\/strong><\/p><p>Not\u00edcia do <a href=\"https:\/\/criancasatortoeadireitos.wordpress.com\/2021\/01\/11\/recorde-de-pedidos-de-ajuda-a-sos-crianca-no-ano-passado\/\" target=\"_blank\" rel=\"noopener\">Jornal de Not\u00edcias<\/a> de 9 de janeiro com declara\u00e7\u00f5es de Manuel Coutinho.<\/p><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-2582\" aria-expanded=\"false\">February<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2582\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-2582\" tabindex=\"0\" hidden=\"hidden\"><p><strong>Covid-19. Isolamento elevou ansiedade ppara n\u00edveis disfuncionais em 10% de crian\u00e7as em estudo<\/strong><\/p><p>Not\u00edcia do <a href=\"https:\/\/expresso.pt\/coronavirus\/2021-02-05-Covid-19.-Isolamento-elevou-ansiedade-para-niveis-disfuncionais-em-10-de-criancas-em-estudo?fbclid=IwAR2bNNN9rKVOToSRzUHXNCcD0-EG3MuhqQB9je5CbOD5IgPsrkfz-V87mnc\" target=\"_blank\" rel=\"noopener\">Expresso <\/a>de 5 de fevereiro com declara\u00e7\u00f5es de Fernanda Salvaterra.<\/p><p><span style=\"font-family: lato, helvetica neue, helvetica, arial, sans-serif;\"><strong>Estudo com crian\u00e7as em ambiente familiar revela elevados estados de ansiedade<\/strong><\/span><br><span style=\"font-family: lato, helvetica neue, helvetica, arial, sans-serif;\">Not\u00edcia da <a href=\"https:\/\/criancasatortoeadireitos.wordpress.com\/2021\/02\/05\/estudo-com-criancas-em-ambiente-familiar-revela-elevados-estados-de-ansiedade-declaracoes-de-fernanda-salvaterra-do-iac-a-antena1\/\" target=\"_blank\" rel=\"noopener\">Antena1<\/a> de 5 de fevereiro com declara\u00e7\u00f5es de Fernanda Salvaterra.<\/span><\/p><p><span style=\"font-family: lato, helvetica neue, helvetica, arial, sans-serif;\"><strong>Isolamento elevou ansiedade para n\u00edveis disfuncionais em 10% de crian\u00e7as de estudo<\/strong><\/span><br><span style=\"font-family: lato, helvetica neue, helvetica, arial, sans-serif;\">Not\u00edcia da <a href=\"https:\/\/criancasatortoeadireitos.wordpress.com\/2021\/02\/05\/isolamento-elevou-ansiedade-para-niveis-disfuncionais-em-10-de-criancas-em-estudo-estudo-do-iac\/\" target=\"_blank\" rel=\"noopener\">TSF<\/a> de 5 de fevereiro com declara\u00e7\u00f5es de Fernanda Salvaterra.<\/span><\/p><p><span style=\"font-family: lato, helvetica neue, helvetica, arial, sans-serif;\"><strong>Ensino \u00e0 dist\u00e2ncia : pequeno manual para lidar com a nuvem<\/strong><\/span><br><span style=\"font-family: lato, helvetica neue, helvetica, arial, sans-serif;\">Not\u00edcia do <a href=\"https:\/\/criancasatortoeadireitos.wordpress.com\/2021\/02\/05\/ensino-a-distancia-pequeno-manual-para-lidar-com-a-nuvem-noticia-com-declaracoes-de-fernanda-salvaterra-do-iac\/\" target=\"_blank\" rel=\"noopener\">Expresso <\/a>de 5 de fevereiro com declara\u00e7\u00f5es de Fernanda Salvaterra.<\/span><\/p><p><span style=\"font-family: lato, helvetica neue, helvetica, arial, sans-serif;\"><strong>Alerta Premika : comportamentos arriscados das crian\u00e7as no digital e a media\u00e7\u00e3o parental em di\u00e1logo com a investiga\u00e7\u00e3o<\/strong><\/span><br><span style=\"font-family: lato, helvetica neue, helvetica, arial, sans-serif;\">Artigo de Cl\u00e1udia Manata (IAC) e Teresa Sofia Castro (UNL) publicado na revista <a href=\"https:\/\/documentcloud.adobe.com\/link\/review?uri=urn%3Aaaid%3Ascds%3AUS%3A4538b209-2545-4db6-aabe-d853fc5144ff&amp;fbclid=IwAR3N7N-wS7xG5FokfTj3yWwUzhdcu25ZR0xMVL93lEPxeVQjXj97nh2R5fY#pageNum=17\" target=\"_blank\" rel=\"noopener\">Desenvolvescer &#8211; Reflex\u00f5es sobre a Inf\u00e2ncia e a Fam\u00edlia n.\u00ba 11 (fev. 2021), p. 11-17<\/a><\/span><\/p><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-2583\" aria-expanded=\"false\">March<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2583\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-2583\" tabindex=\"0\" hidden=\"hidden\"><h5><span style=\"font-family: lato, 'helvetica neue', helvetica, arial, sans-serif; color: #000000;\"><strong>Margarida Gaspar de Matos defende &#8220;necessidade urgente&#8221; de planear a educa\u00e7\u00e3o e o futuro<\/strong><\/span><\/h5><p>Not\u00edcia do <a href=\"https:\/\/criancasatortoeadireitos.wordpress.com\/2021\/03\/08\/margarida-gaspar-de-matos-defende-necessidade-urgente-de-planear-a-educacao-no-futuro\/\" target=\"_blank\" rel=\"noopener\" data-cke-saved-href=\"https:\/\/criancasatortoeadireitos.wordpress.com\/2021\/03\/08\/margarida-gaspar-de-matos-defende-necessidade-urgente-de-planear-a-educacao-no-futuro\/\">P\u00fablico<\/a> de 3 de mar\u00e7o. O IAC \u00e9 mencionado na not\u00edcia.<\/p><p><span style=\"font-family: lato, 'helvetica neue', helvetica, arial, sans-serif; color: #000000;\"><strong>Amor vence lei da ado\u00e7\u00e3o<\/strong><\/span><br><span style=\"font-family: lato, helvetica neue, helvetica, arial, sans-serif;\">Not\u00edcia da <a href=\"https:\/\/criancasatortoeadireitos.wordpress.com\/2021\/04\/07\/amor-vence-lei-da-adocao\/\" target=\"_blank\" rel=\"noopener\" data-cke-saved-href=\"https:\/\/criancasatortoeadireitos.wordpress.com\/2021\/04\/07\/amor-vence-lei-da-adocao\/\">Vis\u00e3o<\/a> de 12 de mar\u00e7o com declara\u00e7\u00f5es de Dulce Rocha.<\/span><\/p><p><span style=\"font-family: lato, 'helvetica neue', helvetica, arial, sans-serif; color: #000000;\"><strong>Ol\u00e1, estou aqui para ajudar: um ano de confinamento<\/strong><\/span><\/p><p>Reportagem do <a href=\"https:\/\/criancasatortoeadireitos.wordpress.com\/2021\/03\/19\/ola-estou-aqui-para-ajudar-um-ano-de-confinamento-reportagem-do-expresso-com-declaracoes-de-manuel-coutinho-do-iac\/\" target=\"_blank\" rel=\"noopener\" data-cke-saved-href=\"https:\/\/criancasatortoeadireitos.wordpress.com\/2021\/03\/19\/ola-estou-aqui-para-ajudar-um-ano-de-confinamento-reportagem-do-expresso-com-declaracoes-de-manuel-coutinho-do-iac\/\">Expresso<\/a><a href=\"https:\/\/expresso.pt\/coronavirus\/2021-02-05-Covid-19.-Isolamento-elevou-ansiedade-para-niveis-disfuncionais-em-10-de-criancas-em-estudo?fbclid=IwAR2bNNN9rKVOToSRzUHXNCcD0-EG3MuhqQB9je5CbOD5IgPsrkfz-V87mnc\" target=\"_blank\" rel=\"noopener\" data-cke-saved-href=\"https:\/\/expresso.pt\/coronavirus\/2021-02-05-Covid-19.-Isolamento-elevou-ansiedade-para-niveis-disfuncionais-em-10-de-criancas-em-estudo?fbclid=IwAR2bNNN9rKVOToSRzUHXNCcD0-EG3MuhqQB9je5CbOD5IgPsrkfz-V87mnc\"> <\/a>de 13 de mar\u00e7o com declara\u00e7\u00f5es de Manuel Coutinho.<\/p><p><span style=\"font-family: lato, 'helvetica neue', helvetica, arial, sans-serif; color: #000000;\"><strong>Participa\u00e7\u00e3o de Manuel Coutinho no programa &#8220;No Ber\u00e7o da Vida&#8221; de 21 de mar\u00e7o. <\/strong><\/span><br>V\u00eddeo <a href=\"https:\/\/fb.watch\/4o92SsZQX1\/\" target=\"_blank\" rel=\"noopener\" data-cke-saved-href=\"https:\/\/fb.watch\/4o92SsZQX1\/\">aqui<\/a><\/p><p><span style=\"font-family: lato, 'helvetica neue', helvetica, arial, sans-serif; color: #000000;\"><strong>Participa\u00e7\u00e3o de Dulce Rocha no programa Sociedade Civil sobre pobreza infantil<\/strong><\/span><\/p><p>V\u00eddeo do programa Sociedade Civil de 30 de mar\u00e7o <a href=\"https:\/\/www.youtube.com\/watch?v=iWJb7XcTCaw&amp;t=3s\" target=\"_blank\" rel=\"noopener\" data-cke-saved-href=\"https:\/\/www.youtube.com\/watch?v=iWJb7XcTCaw&amp;t=3s\">aqui<\/a><\/p><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"4\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-2584\" aria-expanded=\"false\">April<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2584\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-2584\" tabindex=\"0\" hidden=\"hidden\"><p><span style=\"font-family: lato, 'helvetica neue', helvetica, arial, sans-serif; color: #000000;\"><strong>Educa\u00e7\u00e3o a tempo pelos Direitos e Prote\u00e7\u00e3o das Crian\u00e7as<\/strong><\/span><\/p><p>Not\u00edcia do <a href=\"https:\/\/criancasatortoeadireitos.wordpress.com\/2021\/04\/22\/educacao-a-tempo-pelos-direitos-e-protecao-das-criancas\/\" target=\"_blank\" rel=\"noopener\"><em>Not\u00edcias de Loures<\/em><\/a> de 3 de abril. Dulce Rocha e Fernanda Salvaterra s\u00e3o mencionadas na not\u00edcia.<\/p><p><span style=\"color: #000000;\"><strong><span class=\"TextRun SCXW55709616 BCX0\" lang=\"PT-PT\" xml:lang=\"PT-PT\" data-contrast=\"none\"><span class=\"NormalTextRun SCXW55709616 BCX0\">Participa\u00e7\u00e3o de Manuel Coutinho no programa \u201cNo Ber\u00e7o da Vida\u201d de 7 de abril. <\/span><\/span><\/strong><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW55709616 BCX0\"><span class=\"SCXW55709616 BCX0\"> <\/span> <br class=\"SCXW55709616 BCX0\"><\/span><span class=\"TextRun SCXW55709616 BCX0\" lang=\"PT-PT\" data-contrast=\"none\" xml:lang=\"PT-PT\"><span class=\"NormalTextRun SCXW55709616 BCX0\">V\u00eddeo <\/span><\/span><a href=\"https:\/\/www.facebook.com\/460763678043432\/videos\/499686617703542\"><span class=\"TextRun Underlined SCXW55709616 BCX0\" lang=\"PT-PT\" xml:lang=\"PT-PT\" data-contrast=\"none\"><span class=\"NormalTextRun SCXW55709616 BCX0\" data-ccp-charstyle=\"Hyperlink\">aqui<\/span><\/span><\/a><\/p><p><span style=\"color: #000000;\"><strong>Em Portugal, cerca de 70 crian\u00e7as s\u00e3o tiradas por ano das ruas<\/strong><\/span><\/p><p>Not\u00edcia da <a href=\"https:\/\/www.tsf.pt\/portugal\/sociedade\/em-portugal-cerca-de-70-criancas-sao-tiradas-por-ano-das-ruas-13559693.html\">TSF<\/a> de 12 de abril de 2021 com declara\u00e7\u00f5es de Matilde Sirgado.<\/p><p><span style=\"color: #000000;\"><strong>Entrevista de Matilde Sirgado \u00e0 TSF no \u00e2mbito do Dia Mundial das Crian\u00e7as de Rua &#8211; 12 de abril<\/strong><\/span><\/p><p>Entrevista <a href=\"https:\/\/www.youtube.com\/watch?v=UjfumVEmodU\">aqui<\/a><\/p><p><span style=\"font-family: lato, 'helvetica neue', helvetica, arial, sans-serif; color: #000000;\"><strong>Div\u00f3rcios abaixo da m\u00e9dia. Mas os n\u00fameros n\u00e3o refletem o que se passa entre paredes de casa<\/strong><\/span><\/p><p>Not\u00edcia do <a href=\"https:\/\/criancasatortoeadireitos.wordpress.com\/2021\/04\/28\/divorcios-abaixo-da-media-mas-os-numeros-nao-refletem-o-que-se-passa-entre-paredes-de-casa\/\" target=\"_blank\" rel=\"noopener\">Expresso <\/a>de 14 de abril com declara\u00e7\u00f5es de Fernanda Salvaterra.<\/p><p><span style=\"font-family: lato, 'helvetica neue', helvetica, arial, sans-serif; color: #000000;\"><strong>Abril &#8211; M\u00eas do La\u00e7o Azul<\/strong><\/span><\/p><p><span style=\"font-family: lato, helvetica neue, helvetica, arial, sans-serif;\"><a href=\"https:\/\/www.youtube.com\/watch?v=TB8Y1KTXiLs\" target=\"_blank\" rel=\"noopener\">Programa<\/a> &#8220;Os Vizinhos do Presidente&#8221; da <a href=\"https:\/\/radiobelem.jf-belem.pt\/\" target=\"_blank\" rel=\"noopener\">R\u00e1dio Bel\u00e9m<\/a> de 17 de abril com a participa\u00e7\u00e3o de Manuel Coutinho.<\/span><\/p><p><span style=\"color: #000000;\"><strong><span class=\"TextRun SCXW55709616 BCX0\" lang=\"PT-PT\" xml:lang=\"PT-PT\" data-contrast=\"none\"><span class=\"NormalTextRun SCXW55709616 BCX0\">Participa\u00e7\u00e3o de Manuel Coutinho no programa \u201cNo Ber\u00e7o da Vida\u201d de 21 de abril. <\/span><\/span><\/strong><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW55709616 BCX0\"><span class=\"SCXW55709616 BCX0\"> <\/span> <br class=\"SCXW55709616 BCX0\"><\/span><span class=\"TextRun SCXW55709616 BCX0\" lang=\"PT-PT\" data-contrast=\"none\" xml:lang=\"PT-PT\"><span class=\"NormalTextRun SCXW55709616 BCX0\">V\u00eddeo <\/span><\/span><a href=\"https:\/\/www.facebook.com\/460763678043432\/videos\/465249998137915\"><span class=\"TextRun Underlined SCXW55709616 BCX0\" lang=\"PT-PT\" xml:lang=\"PT-PT\" data-contrast=\"none\"><span class=\"NormalTextRun SCXW55709616 BCX0\" data-ccp-charstyle=\"Hyperlink\">aqui<\/span><\/span><\/a><\/p><p><span style=\"font-family: lato, 'helvetica neue', helvetica, arial, sans-serif; color: #000000;\"><strong>M\u00fasica para humanizar os hospitais<\/strong><\/span><\/p><p><span style=\"font-family: lato, helvetica neue, helvetica, arial, sans-serif;\">Not\u00edcia da <a href=\"https:\/\/sicnoticias.pt\/janela-de-esperanca\/temas\/artes\/2021-04-21-Musica-para-humanizar-os-hospitais-8f1cee45\" target=\"_blank\" rel=\"noopener\">SIC Not\u00edcias <\/a>de 22 de abril. O IAC \u00e9 mencionado na not\u00edcia.<\/span><\/p><p><span style=\"font-family: lato, 'helvetica neue', helvetica, arial, sans-serif; color: #000000;\"><strong>DGS lan\u00e7a &#8220;Carta da Crian\u00e7a nos cuidados de sa\u00fade prim\u00e1rios&#8221;<\/strong><\/span><br><span style=\"font-family: noticia text, georgia, times new roman, serif;\">Not\u00edcia do <a href=\"https:\/\/24.sapo.pt\/atualidade\/artigos\/dgs-lanca-carta-da-crianca-nos-cuidados-de-saude-primarios\" target=\"_blank\" rel=\"noopener\">Sapo24<\/a> de 24 de abril de 2021. O IAC \u00e9 mencionado na not\u00edcia.<\/span><\/p><p><span style=\"font-family: lato, 'helvetica neue', helvetica, arial, sans-serif; color: #000000;\"><strong>DGS lan\u00e7a &#8220;Carta da Crian\u00e7a nos cuidados de sa\u00fade prim\u00e1rios&#8221;<\/strong><\/span><br><span style=\"font-family: noticia text, georgia, times new roman, serif;\">Not\u00edcia da <a href=\"https:\/\/www.rtp.pt\/noticias\/pais\/dgs-lanca-carta-da-crianca-nos-cuidados-de-saude-primarios_a1314874\" target=\"_blank\" rel=\"noopener\">Antena 1<\/a> de 24 de abril de 2021 com declara\u00e7\u00f5es de Melanie Tavares.<\/span><\/p><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"5\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-2585\" aria-expanded=\"false\">May<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2585\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-2585\" tabindex=\"0\" hidden=\"hidden\"><p><span style=\"font-family: lato, 'helvetica neue', helvetica, arial, sans-serif; color: #000000;\"><strong>Projeto de mentoria para alunos de Penela<\/strong><\/span><br><span style=\"font-family: noticia text, georgia, times new roman, serif;\">Not\u00edcia do <a href=\"https:\/\/criancasatortoeadireitos.wordpress.com\/2021\/06\/08\/projecto-de-mentoria-para-alunos-de-penela\/\" target=\"_blank\" rel=\"noopener\">Di\u00e1rio de Coimbra<\/a> de 12 de maio de 2021. O IAC \u00e9 mencionado na not\u00edcia.<\/span><\/p><p><span style=\"font-family: lato, 'helvetica neue', helvetica, arial, sans-serif; color: #000000;\"><strong>Podiatersidoeu. O que explica que um pai se esque\u00e7a de um filho no carro?<\/strong><\/span><\/p><p>Not\u00edcia do <a href=\"https:\/\/criancasatortoeadireitos.wordpress.com\/2021\/05\/20\/podiatersidoeu-o-que-explica-que-um-pai-se-esqueca-de-um-filho-no-carro-e-como-se-recupera-do-trauma-noticia-com-declaracoes-de-fernanda-salvaterra-do-iac\/\" target=\"_blank\" rel=\"noopener\">Observador <\/a>de 15 de maio com declara\u00e7\u00f5es de Fernanda Salvaterra.<\/p><p><span class=\"TextRun SCXW55709616 BCX0\" lang=\"PT-PT\" data-contrast=\"none\" xml:lang=\"PT-PT\"><span class=\"NormalTextRun SCXW55709616 BCX0\"><span style=\"color: #000000;\"><strong>Participa\u00e7\u00e3o de Manuel Coutinho no programa \u201cNo Ber\u00e7o da Vida\u201d de 19 de maio<\/strong><\/span>.<\/span><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW55709616 BCX0\"><span class=\"SCXW55709616 BCX0\"> <\/span> <br class=\"SCXW55709616 BCX0\"><\/span><span class=\"TextRun SCXW55709616 BCX0\" lang=\"PT-PT\" data-contrast=\"none\" xml:lang=\"PT-PT\"><span class=\"NormalTextRun SCXW55709616 BCX0\">V\u00eddeo <\/span><\/span><a href=\"https:\/\/www.facebook.com\/460763678043432\/videos\/132380405521812\"><span class=\"TextRun Underlined SCXW55709616 BCX0\" lang=\"PT-PT\" xml:lang=\"PT-PT\" data-contrast=\"none\"><span class=\"NormalTextRun SCXW55709616 BCX0\" data-ccp-charstyle=\"Hyperlink\">aqui<\/span><\/span><\/a><\/p><p><span style=\"font-family: lato, 'helvetica neue', helvetica, arial, sans-serif; color: #000000;\"><strong>\u00c9 preciso lembrar as crian\u00e7as desaparecidas<\/strong><\/span><\/p><p>Not\u00edcia da <a href=\"https:\/\/criancasatortoeadireitos.wordpress.com\/2021\/05\/24\/e-preciso-lembrar-as-criancas-desaparecidas\/\" target=\"_blank\" rel=\"noopener\">Sol<\/a> de 22 de maio. O IAC \u00e9 mencionado na not\u00edcia.<\/p><p><span style=\"font-family: lato, 'helvetica neue', helvetica, arial, sans-serif; color: #000000;\"><strong>PJ recebeu cerca de 1.000 <\/strong><strong>participa\u00e7\u00f5es<\/strong><strong> de crian\u00e7as e jovens at\u00e9 aos 18 anos desaparecidos em 2020.<\/strong><\/span><\/p><p>Not\u00edcia do <a href=\"https:\/\/criancasatortoeadireitos.wordpress.com\/2021\/05\/29\/pj-recebeu-cerca-de-1-000-participacoes-de-criancas-e-jovens-ate-aos-18-anos-desaparecidos-em-2020\/\" target=\"_blank\" rel=\"noopener\">Observador <\/a>de 25 de maio com declara\u00e7\u00f5es de Dulce Rocha.<\/p><p><span class=\"TextRun SCXW55709616 BCX0\" lang=\"PT-PT\" data-contrast=\"none\" xml:lang=\"PT-PT\"><span class=\"NormalTextRun SCXW55709616 BCX0\"><span style=\"color: #000000;\"><strong>Participa\u00e7\u00e3o de Manuel Coutinho no programa \u201cNo Ber\u00e7o da Vida\u201d de 26 de maio<\/strong><\/span>.<\/span><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW55709616 BCX0\"><span class=\"SCXW55709616 BCX0\"> <\/span> <br class=\"SCXW55709616 BCX0\"><\/span><span class=\"TextRun SCXW55709616 BCX0\" lang=\"PT-PT\" data-contrast=\"none\" xml:lang=\"PT-PT\"><span class=\"NormalTextRun SCXW55709616 BCX0\">V\u00eddeo <\/span><\/span><a href=\"https:\/\/www.facebook.com\/460763678043432\/videos\/481796419568433\"><span class=\"TextRun Underlined SCXW55709616 BCX0\" lang=\"PT-PT\" xml:lang=\"PT-PT\" data-contrast=\"none\"><span class=\"NormalTextRun SCXW55709616 BCX0\" data-ccp-charstyle=\"Hyperlink\">aqui<\/span><\/span><\/a><\/p><p><span style=\"font-family: lato, 'helvetica neue', helvetica, arial, sans-serif; color: #000000;\"><strong>Em Foco &#8211; Dia Mundial da Crian\u00e7a<\/strong><\/span><br><span style=\"font-family: noticia text, georgia, times new roman, serif;\">Artigo do <a href=\"https:\/\/criancasatortoeadireitos.wordpress.com\/2021\/06\/07\/em-foco-dia-mundial-da-crianca\/\" target=\"_blank\" rel=\"noopener\">Expresso<\/a> de 28 de maio de 2021. O IAC \u00e9 mencionado no artigo.<\/span><\/p><p><span style=\"color: #000000;\"><strong>Bullying: &#8220;As pessoas ficam marcadas para sempre&#8221;, diz especialista<\/strong><\/span><\/p><p>Not\u00edcia da <a href=\"https:\/\/criancasatortoeadireitos.wordpress.com\/2021\/05\/31\/bullying-as-pessoas-ficam-marcadas-para-sempre-diz-especialista-noticia-com-declaracoes-de-melanie-tavares-do-iac\/\" target=\"_blank\" rel=\"noopener\">TVI <\/a>de 29 de maio com declara\u00e7\u00f5es de Melanie Tavares.<\/p><p><span style=\"font-family: lato, 'helvetica neue', helvetica, arial, sans-serif; color: #000000;\"><strong>Debate sobre crian\u00e7as em contexto de viol\u00eancia dom\u00e9stica marcado para o Dia da Crian\u00e7a<\/strong><\/span><\/p><p>Not\u00edcia do <a href=\"https:\/\/criancasatortoeadireitos.wordpress.com\/2021\/06\/01\/debate-sobre-criancas-em-contexto-de-violencia-domestica-marcado-para-o-dia-da-crianca\/\" target=\"_blank\" rel=\"noopener\">i<\/a> de 31 de maio. Manuela Eanes e Dulce Rocha s\u00e3o mencionadas na not\u00edcia.<\/p><p><span style=\"font-family: lato, 'helvetica neue', helvetica, arial, sans-serif; color: #000000;\"><strong>&#8220;Campanha Primeiros Anos de Vida&#8221;<\/strong><\/span><br><span style=\"font-family: lato, helvetica neue, helvetica, arial, sans-serif;\">Presen\u00e7a de Dulce Rocha no programa a <a href=\"https:\/\/www.youtube.com\/watch?v=6jVzpfqiBkQ&amp;t=373s\" target=\"_blank\" rel=\"noopener\" data-cke-saved-href=\"https:\/\/www.youtube.com\/watch?v=6jVzpfqiBkQ&amp;t=373s\">F\u00e9 dos Homens<\/a> da RTP2 no dia 31 de maio de 2021.<\/span><\/p><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"6\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-2586\" aria-expanded=\"false\">June<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2586\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"6\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-2586\" tabindex=\"0\" hidden=\"hidden\"><p><span style=\"font-family: lato, 'helvetica neue', helvetica, arial, sans-serif; color: #000000;\"><strong>Atividades gr\u00e1tis animam crian\u00e7as<\/strong><\/span><br><span style=\"font-family: noticia text, georgia, times new roman, serif;\">Not\u00edcia do <a href=\"https:\/\/criancasatortoeadireitos.wordpress.com\/2021\/06\/30\/atividades-gratis-animam-criancas-noticia-com-declaracoes-de-paula-duarte-do-iac\/\" target=\"_blank\" rel=\"noopener\" data-cke-saved-href=\"https:\/\/criancasatortoeadireitos.wordpress.com\/2021\/06\/30\/atividades-gratis-animam-criancas-noticia-com-declaracoes-de-paula-duarte-do-iac\/\">Di\u00e1rio de Coimbra<\/a> de 1 de junho de 2021. A not\u00edcia cont\u00e9m declara\u00e7\u00f5es de Paula Duarte.<\/span><\/p><p><span style=\"font-family: lato, 'helvetica neue', helvetica, arial, sans-serif; color: #000000;\"><strong>PSP prolonga at\u00e9 final do ano prazo das pulseiras do programa Estou Aqu\u00ed! Crian\u00e7as<\/strong><\/span><br><span style=\"font-family: noticia text, georgia, times new roman, serif;\">Not\u00edcia da <a href=\"https:\/\/criancasatortoeadireitos.wordpress.com\/2021\/06\/10\/psp-prolonga-ate-final-do-ano-prazo-das-pulseiras-do-programa-estou-aqui-criancas\/\" target=\"_blank\" rel=\"noopener\" data-cke-saved-href=\"https:\/\/criancasatortoeadireitos.wordpress.com\/2021\/06\/10\/psp-prolonga-ate-final-do-ano-prazo-das-pulseiras-do-programa-estou-aqui-criancas\/\">TSF<\/a> de 2 de junho de 2021. O IAC \u00e9 mencionado na not\u00edcia.<\/span><\/p><p><span style=\"font-family: lato, 'helvetica neue', helvetica, arial, sans-serif; color: #000000;\"><strong>Morreu o escritor Ant\u00f3nio Torrado<\/strong><\/span><\/p><p>Not\u00edcia do <a href=\"https:\/\/observador.pt\/2021\/06\/11\/morreu-o-escritor-antonio-torrado\/\" target=\"_blank\" rel=\"noopener\" data-cke-saved-href=\"https:\/\/observador.pt\/2021\/06\/11\/morreu-o-escritor-antonio-torrado\/\">Observador <\/a>de 11 de junho. O IAC \u00e9 mencionado na not\u00edcia.<\/p><p><span style=\"font-family: lato, 'helvetica neue', helvetica, arial, sans-serif; color: #000000;\"><strong>Falta de pessoal n\u00e3o docente prop\u00edcia viol\u00eancia nas escolas<\/strong><\/span><\/p><p><span style=\"font-family: lato, helvetica neue, helvetica, arial, sans-serif;\">Not\u00edcia do <a href=\"https:\/\/criancasatortoeadireitos.wordpress.com\/2021\/07\/01\/falta-de-pessoal-nao-docente-propicia-violencia-nas-escolas-noticia-com-declaracoes-de-melanie-tavares-do-iac\/\" target=\"_blank\" rel=\"noopener\" data-cke-saved-href=\"https:\/\/criancasatortoeadireitos.wordpress.com\/2021\/07\/01\/falta-de-pessoal-nao-docente-propicia-violencia-nas-escolas-noticia-com-declaracoes-de-melanie-tavares-do-iac\/\">Sem Mais<\/a> de 11 de junho com declara\u00e7\u00f5es de Melanie Tavares.<\/span><\/p><p><span style=\"font-family: lato, 'helvetica neue', helvetica, arial, sans-serif; color: #000000;\"><strong>Matilde Rosa Ara\u00fajo &#8211; A Voz das Crian\u00e7as, na escritora\/professora exemplar<\/strong><\/span><\/p><p>Not\u00edcia do <a href=\"https:\/\/criancasatortoeadireitos.wordpress.com\/2021\/06\/30\/matilde-rosa-araujo-a-voz-das-criancas-na-escritora-professora-exemplar\/\" target=\"_blank\" rel=\"noopener\" data-cke-saved-href=\"https:\/\/criancasatortoeadireitos.wordpress.com\/2021\/06\/30\/matilde-rosa-araujo-a-voz-das-criancas-na-escritora-professora-exemplar\/\">Jornal de Letras<\/a> de 16 de junho. O IAC \u00e9 mencionado na not\u00edcia.<\/p><p><span style=\"font-family: lato, 'helvetica neue', helvetica, arial, sans-serif; color: #000000;\"><strong>Assembleia da Rep\u00fablica recorda escritor Ant\u00f3nio Torrado como &#8220;maravilhoso contador de hist\u00f3rias&#8221;<\/strong><\/span><\/p><p>Not\u00edcia do <a href=\"https:\/\/criancasatortoeadireitos.wordpress.com\/2021\/06\/23\/assembleia-da-republica-recorda-escritor-antonio-torrado-como-maravilhoso-contador-de-historias\/\" target=\"_blank\" rel=\"noopener\" data-cke-saved-href=\"https:\/\/criancasatortoeadireitos.wordpress.com\/2021\/06\/23\/assembleia-da-republica-recorda-escritor-antonio-torrado-como-maravilhoso-contador-de-historias\/\">Sapo Mag<\/a> de 18 de junho. <span style=\"font-family: noticia text, georgia, times new roman, serif;\">O IAC \u00e9 mencionado no artigo.<\/span><\/p><p><span style=\"font-family: lato, 'helvetica neue', helvetica, arial, sans-serif; color: #000000;\"><strong>A <\/strong><strong>incr\u00edvel<\/strong><strong> hist\u00f3ria do beb\u00e9 Noha<\/strong><\/span><br><span style=\"font-family: noticia text, georgia, times new roman, serif;\">Artigo do <a href=\"https:\/\/criancasatortoeadireitos.wordpress.com\/2021\/06\/23\/a-incrivel-historia-do-bebe-noah\/\" target=\"_blank\" rel=\"noopener\" data-cke-saved-href=\"https:\/\/criancasatortoeadireitos.wordpress.com\/2021\/06\/23\/a-incrivel-historia-do-bebe-noah\/\">Sol<\/a> de 19 de junho de 2021. O IAC \u00e9 mencionado no artigo.<\/span><\/p><p><span style=\"font-family: lato, 'helvetica neue', helvetica, arial, sans-serif; color: #000000;\"><strong>Longe da vista, dor no cora\u00e7\u00e3o<\/strong><\/span><\/p><p><span style=\"font-family: lato, helvetica neue, helvetica, arial, sans-serif;\">Reportagem do <a href=\"https:\/\/criancasatortoeadireitos.wordpress.com\/2021\/06\/30\/longe-da-vista-dor-no-coracao-reportagem-com-declaracoes-de-manuel-coutinho-do-iac\/\" target=\"_blank\" rel=\"noopener\" data-cke-saved-href=\"https:\/\/criancasatortoeadireitos.wordpress.com\/2021\/06\/30\/longe-da-vista-dor-no-coracao-reportagem-com-declaracoes-de-manuel-coutinho-do-iac\/\">Not\u00edcias Magazine<\/a> de 27 de junho com declara\u00e7\u00f5es de Manuel Coutinho.<\/span><\/p><p><span class=\"TextRun SCXW55709616 BCX0\" lang=\"PT-PT\" data-contrast=\"none\" xml:lang=\"PT-PT\"><span class=\"NormalTextRun SCXW55709616 BCX0\"><span style=\"color: #000000;\"><strong>Participa\u00e7\u00e3o de Manuel Coutinho no programa \u201cNo Ber\u00e7o da Vida\u201d de 30 de junho<\/strong><\/span>.<\/span><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW55709616 BCX0\"><span class=\"SCXW55709616 BCX0\"> <\/span> <br class=\"SCXW55709616 BCX0\"><\/span><span class=\"TextRun SCXW55709616 BCX0\" lang=\"PT-PT\" data-contrast=\"none\" xml:lang=\"PT-PT\"><span class=\"NormalTextRun SCXW55709616 BCX0\">V\u00eddeo <\/span><\/span><a href=\"https:\/\/www.facebook.com\/460763678043432\/videos\/213965400607667\"><span class=\"TextRun Underlined SCXW55709616 BCX0\" lang=\"PT-PT\" xml:lang=\"PT-PT\" data-contrast=\"none\"><span class=\"NormalTextRun SCXW55709616 BCX0\" data-ccp-charstyle=\"Hyperlink\">aqui<\/span><\/span><\/a><\/p><p><span style=\"font-family: lato, 'helvetica neue', helvetica, arial, sans-serif; color: #000000;\"><strong>Aumento viol\u00eancia dom\u00e9stica sobre crian\u00e7as<\/strong><\/span><\/p><p><span style=\"font-family: lato, helvetica neue, helvetica, arial, sans-serif;\">Not\u00edcia da <a href=\"https:\/\/www.youtube.com\/watch?v=pFfoVqeaeTE&amp;t=76s\" target=\"_blank\" rel=\"noopener\">TVI <\/a>de 30 de junho com declara\u00e7\u00f5es de Dulce Rocha.<\/span><\/p><p><span style=\"font-family: lato, 'helvetica neue', helvetica, arial, sans-serif; color: #000000;\"><strong>&#8220;A pandemia veio mostrar a fragilidade de todo o <\/strong><strong>sistema<\/strong><strong> social&#8221;<\/strong><\/span><br><span style=\"font-family: noticia text, georgia, times new roman, serif;\">Entrevista de Paula Duarte \u00e0 <a href=\"https:\/\/criancasatortoeadireitos.wordpress.com\/2021\/09\/01\/a-pandemia-veio-mostrar-a-fragilidade-de-todo-o-sistema-social-paula-duarte-do-iac-a-focus-social\/\" target=\"_blank\" rel=\"noopener\">Focus Social <\/a>n\u00ba 19 de junho de 2021. <\/span><\/p><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"7\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-2587\" aria-expanded=\"false\">July<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2587\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"7\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-2587\" tabindex=\"0\" hidden=\"hidden\"><p><span style=\"font-family: lato, 'helvetica neue', helvetica, arial, sans-serif; color: #000000;\"><strong>\u00c9 preciso olhar para o contexto da neglig\u00eancia<\/strong><\/span><br><span style=\"font-family: noticia text, georgia, times new roman, serif;\">Not\u00edcia do <a href=\"https:\/\/criancasatortoeadireitos.wordpress.com\/2021\/07\/01\/e-preciso-olhar-para-o-contexto-da-negligencia-manuel-coutinho-do-iac-ao-correio-da-manha\/\" target=\"_blank\" rel=\"noopener\">Correio da Manh\u00e3<\/a> de 1 de julho. A not\u00edcia cont\u00e9m declara\u00e7\u00f5es de Manuel Coutinho.<\/span><\/p><p><span style=\"font-family: lato, 'helvetica neue', helvetica, arial, sans-serif; color: #000000;\"><strong>Telefone n\u00e3o toma banho, n\u00e3o come e n\u00e3o dorme mas precisa de f\u00e9rias<\/strong><\/span><\/p><p>Not\u00edcia do <a href=\"https:\/\/criancasatortoeadireitos.wordpress.com\/2021\/07\/07\/telefone-nao-toma-banho-nao-come-e-nao-dorme-mas-precisa-de-ferias\/\" target=\"_blank\" rel=\"noopener\">Jornal de Not\u00edcias<\/a> de 2 de julho. O IAC \u00e9 mencionado na not\u00edcia.<\/p><p><span style=\"font-family: lato, 'helvetica neue', helvetica, arial, sans-serif; color: #000000;\"><strong>Manuela Eanes e o menino de ouro<\/strong><\/span><\/p><p>Not\u00edcia do <a href=\"https:\/\/criancasatortoeadireitos.wordpress.com\/2021\/07\/24\/manuela-eanes-e-o-menino-de-ouro\/\" target=\"_blank\" rel=\"noopener\">Nascer do Sol <\/a> de 10 de julho.<\/p><p><span style=\"font-family: lato, 'helvetica neue', helvetica, arial, sans-serif; color: #000000;\"><strong>Quase 600 crian\u00e7as <\/strong><strong>\u00f3rf\u00e3s<\/strong><strong> em Portugal por causa do Covid-19? &#8220;N\u00famero n\u00e3o ser\u00e1 t\u00e3o avassalador&#8221; diz Instituto de Apoio \u00e0 Crian\u00e7a<\/strong><\/span><br><span style=\"font-family: noticia text, georgia, times new roman, serif;\">Not\u00edcia do <a href=\"https:\/\/criancasatortoeadireitos.wordpress.com\/2021\/07\/21\/quase-600-criancas-orfas-em-portugal-por-causa-da-covid-19-numero-nao-sera-tao-avassalador-diz-instituto-de-apoio-a-crianca\/\" target=\"_blank\" rel=\"noopener\">R\u00e1dio Observador<\/a> de 21 de julho de 2021. A not\u00edcia cont\u00e9m declara\u00e7\u00f5es de Dulce Rocha.<\/span><\/p><p><span style=\"font-family: lato, 'helvetica neue', helvetica, arial, sans-serif; color: #000000;\"><strong>Adolescente que empurrou colega disse ao MP que o epis\u00f3dio &#8220;foi apenas uma partida&#8221;<\/strong><\/span><\/p><p>Not\u00edcia do <a href=\"https:\/\/criancasatortoeadireitos.wordpress.com\/2021\/07\/26\/adolescente-que-empurrou-colega-disse-ao-mp-que-o-episodio-foi-apenas-uma-partida\/\" target=\"_blank\" rel=\"noopener\">P\u00fablico<\/a> de 26 de julho. <span style=\"font-family: noticia text, georgia, times new roman, serif;\">A not\u00edcia cont\u00e9m declara\u00e7\u00f5es de Melanie Tavares.<\/span><\/p><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"8\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-2588\" aria-expanded=\"false\">August<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2588\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"8\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-2588\" tabindex=\"0\" hidden=\"hidden\"><p><span style=\"font-family: lato, 'helvetica neue', helvetica, arial, sans-serif; color: #000000;\"><strong>Jovens est\u00e3o a procurar com mais frequ\u00eancia ajuda psicol\u00f3gica<\/strong><\/span><\/p><p><span style=\"font-family: lato, helvetica neue, helvetica, arial, sans-serif;\">Not\u00edcia da<a href=\"https:\/\/www.youtube.com\/watch?v=9-CSRKp3YR4\" target=\"_blank\" rel=\"noopener\"> SIC<\/a><a href=\"https:\/\/www.youtube.com\/watch?v=pFfoVqeaeTE&amp;t=76s\" target=\"_blank\" rel=\"noopener\"> <\/a> de 8 de agosto com a participa\u00e7\u00e3o de Manuel Coutinho.<\/span><\/p><p><span style=\"font-family: lato, 'helvetica neue', helvetica, arial, sans-serif; color: #000000;\"><strong>INEM ajuda mais jovens com problemas psicol\u00f3gicos<\/strong><\/span><br><span style=\"font-family: noticia text, georgia, times new roman, serif;\">Not\u00edcia do <a href=\"https:\/\/criancasatortoeadireitos.wordpress.com\/2021\/08\/09\/inem-ajuda-mais-jovens-com-problemas-psicologicos-noticia-com-declaracoes-de-manuel-coutinho-do-iac\/\" target=\"_blank\" rel=\"noopener\">Jornal de Not\u00edcias<\/a> de 8 de agosto. A not\u00edcia cont\u00e9m declara\u00e7\u00f5es de Manuel Coutinho.<\/span><\/p><p><span style=\"font-family: lato, 'helvetica neue', helvetica, arial, sans-serif; color: #000000;\"><strong>Supremo Tribunal de Justi\u00e7a reduz pena de mulher que abandonou <\/strong><strong>beb\u00e9<\/strong><strong> no lixo em Lisboa para um ano e dez meses de pris\u00e3o<\/strong><\/span><br><span style=\"font-family: noticia text, georgia, times new roman, serif;\">Not\u00edcia do <a href=\"https:\/\/www.dn.pt\/sociedade\/supremo-tribunal-de-justica-reduz-pena-de-mulher-que-abandonou-bebe-no-lixo-em-lisboa-para-um-ano-e-10-meses-de-prisao--14046180.html\" target=\"_blank\" rel=\"noopener\">Di\u00e1rio de Not\u00edcias<\/a> de 19 de agosto de 2021. A not\u00edcia cont\u00e9m declara\u00e7\u00f5es de Dulce Rocha.<\/span><\/p><p><span class=\"TextRun SCXW55709616 BCX0\" lang=\"PT-PT\" style=\"color: #000000;\" data-contrast=\"none\" xml:lang=\"PT-PT\"><span class=\"NormalTextRun SCXW55709616 BCX0\"><strong>Participa\u00e7\u00e3o de Manuel Coutinho no programa \u201cNo Ber\u00e7o da Vida\u201d de 25 de agosto<\/strong>.<\/span><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW55709616 BCX0\"><span class=\"SCXW55709616 BCX0\" style=\"color: #000000;\"> <\/span> <br class=\"SCXW55709616 BCX0\"><\/span><span class=\"TextRun SCXW55709616 BCX0\" lang=\"PT-PT\" data-contrast=\"none\" xml:lang=\"PT-PT\"><span class=\"NormalTextRun SCXW55709616 BCX0\">V\u00eddeo <\/span><\/span><a href=\"https:\/\/www.facebook.com\/460763678043432\/videos\/942345576629277\"><span class=\"TextRun Underlined SCXW55709616 BCX0\" lang=\"PT-PT\" xml:lang=\"PT-PT\" data-contrast=\"none\"><span class=\"NormalTextRun SCXW55709616 BCX0\" data-ccp-charstyle=\"Hyperlink\">aqui<\/span><\/span><\/a><\/p><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"9\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-2589\" aria-expanded=\"false\">September<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2589\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"9\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-2589\" tabindex=\"0\" hidden=\"hidden\"><p><span style=\"font-family: lato, 'helvetica neue', helvetica, arial, sans-serif; color: #000000;\"><strong>Os primeiros anos s\u00e3o fundamentais. Saiba porqu\u00ea<\/strong><\/span><br><span style=\"font-family: noticia text, georgia, times new roman, serif;\">Artigo da <a href=\"https:\/\/criancasatortoeadireitos.wordpress.com\/2021\/10\/07\/os-primeiros-anos-de-vida-de-um-bebe-sao-fundamentais-saiba-porque\/\" target=\"_blank\" rel=\"noopener\">Saber Viver<\/a> n.\u00ba 255, setembro de 2021. A not\u00edcia cont\u00e9m declara\u00e7\u00f5es de Fernanda salvaterra.<\/span><\/p><p><span style=\"font-family: lato, 'helvetica neue', helvetica, arial, sans-serif; color: #000000;\"><strong>Presidente da Rep\u00fablica condecora a pedagoga Ana Vieira de Almeida a t\u00edtulo p\u00f3stumo<\/strong><\/span><br><span style=\"font-family: noticia text, georgia, times new roman, serif;\">Not\u00edcia do <a href=\"https:\/\/observador.pt\/2021\/09\/09\/presidente-da-republica-condecora-a-pedagoga-ana-maria-vieira-de-almeida-a-titulo-postumo\/\" target=\"_blank\" rel=\"noopener\">Observador<\/a> de 9 de setembro de 2021. O IAC \u00e9 mencionado na not\u00edcia.<\/span><\/p><p><span style=\"font-family: lato, 'helvetica neue', helvetica, arial, sans-serif; color: #000000;\"><strong>Guilherme d&#8217;Oliveira Martins <\/strong><strong>apresenta &#8220;Vida plena &#8211; 50 Reflex\u00f5es de um m\u00e9dico&#8221;<\/strong><\/span><br><span style=\"font-family: noticia text, georgia, times new roman, serif;\">Not\u00edcia do <a href=\"https:\/\/otemplario.pt\/livros-2\/guilherme-doliveira-martins-apresenta-vida-plena-50-reflexoes-de-um-medico\/\" target=\"_blank\" rel=\"noopener\">O Templ\u00e1rio<\/a> de 20 de setembro de 2021. Manuela Eanes \u00e9 mencionada na not\u00edcia e os direitos de autor da obra revertem para o IAC.<\/span><\/p><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"10\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-25810\" aria-expanded=\"false\">October<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-25810\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"10\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-25810\" tabindex=\"0\" hidden=\"hidden\"><p><span style=\"font-family: lato, 'helvetica neue', helvetica, arial, sans-serif; color: #000000;\"><strong>Os primeiros anos de vida de um beb\u00e9 s\u00e3o fundamentais. Saiba porqu\u00ea<\/strong><\/span><br><span style=\"font-family: noticia text, georgia, times new roman, serif;\">Artigo da <a href=\"https:\/\/www.saberviver.pt\/bem-estar\/relacoes-e-familia\/primeiros-anos-vida-bebe-fundamentais\/\" target=\"_blank\" rel=\"noopener\">Saber Viver<\/a> de 5 de outubro de 2021 com declara\u00e7\u00f5es de Fernanda Salvaterra.<\/span><\/p><p><span class=\"TextRun SCXW55709616 BCX0\" lang=\"PT-PT\" data-contrast=\"none\" xml:lang=\"PT-PT\"><span class=\"NormalTextRun SCXW55709616 BCX0\"><span style=\"color: #000000;\"><strong>Participa\u00e7\u00e3o de Manuel Coutinho no programa \u201cNo Ber\u00e7o da Vida\u201d de 7 de outubro<\/strong><\/span>.<\/span><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW55709616 BCX0\"><span class=\"SCXW55709616 BCX0\"> <\/span> <br class=\"SCXW55709616 BCX0\"><\/span><span class=\"TextRun SCXW55709616 BCX0\" lang=\"PT-PT\" data-contrast=\"none\" xml:lang=\"PT-PT\"><span class=\"NormalTextRun SCXW55709616 BCX0\">V\u00eddeo <\/span><\/span><a href=\"https:\/\/www.facebook.com\/460763678043432\/videos\/4459203424167213\/\"><span class=\"TextRun Underlined SCXW55709616 BCX0\" lang=\"PT-PT\" xml:lang=\"PT-PT\" data-contrast=\"none\"><span class=\"NormalTextRun SCXW55709616 BCX0\" data-ccp-charstyle=\"Hyperlink\">aqui<\/span><\/span><\/a><\/p><p><span style=\"font-family: lato, 'helvetica neue', helvetica, arial, sans-serif; color: #000000;\"><strong>Em Nome da Lei Liberdade Religiosa vs Direito \u00e0 Vida<\/strong><\/span><br><span style=\"font-family: noticia text, georgia, times new roman, serif;\">Debate na <a href=\"https:\/\/podcasts.apple.com\/pt\/podcast\/em-nome-da-lei-liberdade-religiosa-vs-direito-%C3%A0-vida\/id1050576408?i=1000538766866\" target=\"_blank\" rel=\"noopener\">R\u00e1dio Renascen\u00e7a<\/a> no dia 16 de outubro de 2021 com a participa\u00e7\u00e3o de Dulce Rocha sobre<\/span>a recusa de tratamento por um jovem de 16 anos, motivada por confiss\u00e3o religiosa.<\/p><p><span style=\"font-family: lato, 'helvetica neue', helvetica, arial, sans-serif; color: #000000;\"><strong>Vidas marcadas pelo bullying<\/strong><\/span><br><a href=\"https:\/\/tvi.iol.pt\/doisas10\/geral\/18-10-2021\/vidas-marcadas-pelo-bullying\" target=\"_blank\" rel=\"noopener\">Programa Dois \u00e0s 10 <\/a>da TVI de 18 de outubro de 2021 com a participa\u00e7\u00e3o de Melanie Tavares.<\/p><p><span style=\"font-family: lato, 'helvetica neue', helvetica, arial, sans-serif; color: #000000;\"><strong>Mangualde recebeu a\u00e7\u00e3o de sensibiliza\u00e7\u00e3o contra a viol\u00eancia<\/strong><\/span><br><span style=\"font-family: noticia text, georgia, times new roman, serif;\">Not\u00edcia do <a href=\"https:\/\/criancasatortoeadireitos.wordpress.com\/2021\/11\/08\/mangualde-recebeu-accao-de-sensibilizacao-contra-a-violencia\/\" target=\"_blank\" rel=\"noopener\">Di\u00e1rio de Viseu<\/a> de 19 de outubro de 2021 na qual \u00e9 mencionado o IAC &#8211; Polo de Coimbra e os t\u00e9cnicos Cristina Barros e Jos\u00e9 Coelho.<\/span><\/p><p><span style=\"font-family: lato, 'helvetica neue', helvetica, arial, sans-serif; color: #000000;\"><strong>Porque que os pais n\u00e3o podem fechar os olhos a &#8220;Squid Game&#8221;<\/strong><\/span><br><span style=\"font-family: noticia text, georgia, times new roman, serif;\">Not\u00edcia do <a href=\"https:\/\/tvi24.iol.pt\/sociedade\/criancas\/porque-e-que-os-pais-nao-podem-fechar-os-olhos-a-squid-game?utm_source=facebook&amp;utm_medium=social&amp;utm_campaign=ed-tvi24&amp;fbclid=IwAR3KXkc6zmWtM2sh9IscQVg3D1bjRMqNaKlLnMOl6dL5O4yeMh6Y56kj2yw\" target=\"_blank\" rel=\"noopener\">TVI24<\/a> de 20 de outubro de 2021 com declara\u00e7\u00f5es de Melanie Tavares.<\/span><\/p><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"11\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-25811\" aria-expanded=\"false\">November<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-25811\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"11\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-25811\" tabindex=\"0\" hidden=\"hidden\"><p><span style=\"font-family: lato, 'helvetica neue', helvetica, arial, sans-serif; color: #000000;\"><strong>CPCJ de Mangualde promoveu confer\u00eancia &#8220;Os Direitos da Crian\u00e7a e o Sistema de Prote\u00e7\u00e3o da Crian\u00e7a e do Jovem&#8221;<\/strong><\/span><br aria-hidden=\"true\"><span style=\"font-family: noticia text, georgia, times new roman, serif;\">Not\u00edcia do <a href=\"https:\/\/iacrianca.us5.list-manage.com\/track\/click?u=1f715fbf2fbf7c13612604bec&amp;id=4be20ee8ce&amp;e=622df3f91a\" target=\"_blank\" rel=\"noopener noreferrer\" data-auth=\"NotApplicable\" data-linkindex=\"48\">Mangualde Online<\/a> do dia 5 de novembro de 2021. A not\u00edcia refere a participa\u00e7\u00e3o de Ana Perdig\u00e3o e Teresa Varela na confer\u00eancia.<\/span><\/p><p><span style=\"font-family: lato, 'helvetica neue', helvetica, arial, sans-serif; color: #000000;\"><strong>Mais de 500 casamentos precoces nos <\/strong><strong>\u00faltimos<\/strong><strong> 5 anos<\/strong><\/span><br aria-hidden=\"true\">Not\u00edcia do <a href=\"https:\/\/iacrianca.us5.list-manage.com\/track\/click?u=1f715fbf2fbf7c13612604bec&amp;id=afe086e285&amp;e=622df3f91a\" target=\"_blank\" rel=\"noopener noreferrer\" data-auth=\"NotApplicable\" data-linkindex=\"49\">Jornal de Not\u00edcias<\/a> de 8 de novembro de 2021. A not\u00edcia menciona a Linha SOS &#8211; Crian\u00e7a 116 111.<\/p><p><span style=\"font-family: lato, 'helvetica neue', helvetica, arial, sans-serif; color: #000000;\"><strong>Aumentam den\u00fancias ao IAC de menores em situa\u00e7\u00e3o de perigo<\/strong><\/span><br aria-hidden=\"true\"><span style=\"font-family: noticia text, georgia, times new roman, serif;\">Not\u00edcia do <a href=\"https:\/\/iacrianca.us5.list-manage.com\/track\/click?u=1f715fbf2fbf7c13612604bec&amp;id=6a769760c3&amp;e=622df3f91a\" target=\"_blank\" rel=\"noopener noreferrer\" data-auth=\"NotApplicable\" data-linkindex=\"47\">Jornal de Not\u00edcias<\/a> de 21 de novembro de 2021 com declara\u00e7\u00f5es de Ana Perdig\u00e3o e Manuel Coutinho.<\/span><\/p><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"12\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-25812\" aria-expanded=\"false\">December<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-25812\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"12\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-25812\" tabindex=\"0\" hidden=\"hidden\"><p><span style=\"font-family: lato, 'helvetica neue', helvetica, arial, sans-serif; color: #000000;\"><strong>N\u00famero de crian\u00e7as adotadas desce h\u00e1 quatro anos e atinge novos m\u00ednimos <\/strong><\/span><br><span style=\"font-family: noticia text, georgia, times new roman, serif;\">Not\u00edcia do <a href=\"https:\/\/criancasatortoeadireitos.wordpress.com\/2021\/12\/09\/numero-de-criancas-adoptadas-desce-ha-quatro-anos-e-atinge-novos-minimos-noticia-com-declaracoes-de-ana-perdigao-do-iac\/\">P\u00fablico<\/a> de 5 de dezembro de 2021 com declara\u00e7\u00f5es de Ana Perdig\u00e3o.<\/span><\/p><p><span style=\"font-family: lato, 'helvetica neue', helvetica, arial, sans-serif; color: #000000;\"><strong>&#8220;Lista de ped\u00f3filos condenados j\u00e1 tem quase seis mil nomes<\/strong><\/span><br><span style=\"font-family: noticia text, georgia, times new roman, serif;\">Not\u00edcia do <a href=\"https:\/\/criancasatortoeadireitos.wordpress.com\/2021\/12\/21\/lista-de-pedofilos-condenados-ja-tem-quase-seis-mil-nomes-noticia-do-jn-com-declaracoes-da-presidente-do-iac-dr-a-dulce-rocha\/\" target=\"_blank\" rel=\"noopener\">Jornal de Not\u00edcias<\/a> de 20 de dezembro de 2021 com declara\u00e7\u00f5es de Dulce Rocha.<\/span><\/p><p><span style=\"font-family: lato, 'helvetica neue', helvetica, arial, sans-serif; color: #000000;\"><strong>Lista de ped\u00f3filos aumenta &#8220;Tem que se alterar a moldura penal para que n\u00e3o saiam com pena suspensa&#8221;<\/strong><\/span><br><span style=\"font-family: noticia text, georgia, times new roman, serif;\">Entrevista da <a href=\"https:\/\/cnnportugal.iol.pt\/videos\/lista-de-pedofilos-aumenta-tem-de-se-alterar-a-moldura-penal-para-que-nao-saiam-com-pena-suspensa\/61c06bd60cf21a10a414f898\" target=\"_blank\" rel=\"noopener\">CNN Portugal<\/a> do dia 20 de dezembro de 2021 a Manuel Coutinho.<\/span><\/p><p><span style=\"font-family: lato, 'helvetica neue', helvetica, arial, sans-serif; color: #000000;\"><strong>Entrevista de Matilde Sirgado \u00e0 revista &#8220;Um Lugar \u00e0 Mesa&#8221;<\/strong><\/span><br><a href=\"https:\/\/www.yumpu.com\/pt\/document\/read\/66066176\/um-lugar-a-mesa-dar-voz-aos-lideres-sociais-n-1\" target=\"_blank\" rel=\"noopener\"><em>Um Lugar \u00e0 Mesa<\/em> .- n. 1 (Dez. 2021), p. 57-61<\/a><\/p><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-436248e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"436248e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d1d55b2\" data-id=\"d1d55b2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fa8b86d elementor-widget elementor-widget-heading\" data-id=\"fa8b86d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-large\">2020<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5cf18ce elementor-tabs-view-vertical elementor-widget elementor-widget-tabs\" data-id=\"5cf18ce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-9741\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-9741\" aria-expanded=\"false\">January<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-9742\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-9742\" aria-expanded=\"false\">February<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-9743\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-9743\" aria-expanded=\"false\">March<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-9744\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"4\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-9744\" aria-expanded=\"false\">April<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-9745\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"5\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-9745\" aria-expanded=\"false\">May<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-9746\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"6\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-9746\" aria-expanded=\"false\">June<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-9747\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"7\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-9747\" aria-expanded=\"false\">July<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-9748\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"8\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-9748\" aria-expanded=\"false\">August<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-9749\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"9\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-9749\" aria-expanded=\"false\">September<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-97410\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"10\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-97410\" aria-expanded=\"false\">October<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-97411\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"11\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-97411\" aria-expanded=\"false\">November<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-97412\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"12\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-97412\" aria-expanded=\"false\">December<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-9741\" aria-expanded=\"false\">January<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-9741\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-9741\" tabindex=\"0\" hidden=\"false\"><h5>Reportagem TVI &#8211; Unidade M\u00f3vel L\u00fadico-Pedag\u00f3gica no Voc\u00ea na TV<\/h5><p>14 de janeiro, Manuela Eanes e Matilde Sirgado estiveram no Programa Voc\u00ea na TV.<\/p><p>Para visualizar a reportagem completa, clique nos links: <a href=\"https:\/\/tvi.iol.pt\/vocenatv\/videos\/tecnicas-do-iac-trabalham-nas-ruas-de-dia-e-de-noite\/5e1efde90cf2c472ec71dedd?jwsource=cl\">Parte 1<\/a> <a href=\"https:\/\/tvi.iol.pt\/vocenatv\/videos\/o-iac-trabalha-com-criancas-em-risco\/5e1efef90cf2c472ec71deea?jwsource=cl\">Parte 2<\/a> <a href=\"https:\/\/tvi.iol.pt\/vocenatv\/videos\/iac-faz-intervencao-em-bairros-sociais\/5e1efab60cf2d5f7c67a0a21?jwsource=cl\">Parte 3<\/a> <a href=\"https:\/\/tvi.iol.pt\/vocenatv\/videos\/iac-promove-os-diretos-da-crianca\/5e1efc630cf2d5f7c67a0a3b\">Parte 4<\/a><\/p><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-9742\" aria-expanded=\"false\">February<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-9742\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-9742\" tabindex=\"0\" hidden=\"hidden\"><h5>Mais do que da viol\u00eancia, professores queixam-se da indisciplina na sala de aula<\/h5><p><a href=\"https:\/\/www.educare.pt\/noticias\/noticia\/ver\/?id=162187&amp;langid=1&amp;fbclid=IwAR2FhM4fMPSb0Wxhm8r0ZLahSPSn8AunolzyWJRPZNMPojy1SHexHLCVE-E\">Artigo<\/a> do site Educare de 24 de fevereiro com declara\u00e7\u00f5es de Cl\u00e1udia Manata da \u00c1rea do Conhecimento e Forma\u00e7\u00e3o.<\/p><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-9743\" aria-expanded=\"false\">March<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-9743\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-9743\" tabindex=\"0\" hidden=\"hidden\"><h5>Linha SOS-Crian\u00e7a<\/h5><p>Entrevista do Dr\u00ba Manuel Coutinho, Secret\u00e1rio-Geral do IAC \u00e0 <a href=\"https:\/\/criancasatortoeadireitos.wordpress.com\/2020\/03\/18\/linha-sos-crianca-entrevista-do-dro-manuel-coutinho-secretario-geral-do-iac-a-rtp3\/\">RTP3<\/a> no dia 18 de mar\u00e7o<\/p><h5>Dizer a verdade \u00e0s crian\u00e7as, mas proteg\u00ea-las de informa\u00e7\u00e3o a mais \u2013 Entrevista de Melanie Tavares do IAC<\/h5><p><a href=\"https:\/\/criancasatortoeadireitos.files.wordpress.com\/2020\/04\/melanie-tavares_a-bola.pdf\">Jornal A Bola<\/a> do dia 24 de mar\u00e7o de 2020.<\/p><h5>Covid-19: Linha SOS-Crian\u00e7a<\/h5><p>Reportagem sobre a LINHA SOS-CRIAN\u00c7A &#8211; <a href=\"https:\/\/kidsmarketeer.sapo.pt\/covid-19-linha-sos-crianca\/\">KIDS MARKETTER<\/a> &#8211; 24\/3\/20<\/p><h5>Grande Entrevista Daniel Sampaio Retidos em Casa: o impacto psicol\u00f3gico e estrat\u00e9gias para superar o isolamento<\/h5><p><a href=\"https:\/\/criancasatortoeadireitos.wordpress.com\/2020\/04\/06\/grande-entrevista-daniel-sampaio-retidos-em-casa-o-impacto-psicologico-e-estrategias-para-superar-o-isolamento\/\">RTP<\/a> 25\/3\/20. O Dr\u00ba Daniel Sampaio \u00e9 membro do Conselho Consultivo do IAC.<\/p><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"4\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-9744\" aria-expanded=\"false\">April<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-9744\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-9744\" tabindex=\"0\" hidden=\"hidden\"><h5>Entrevista de Fernanda Salvaterra do IAC \u00e0 R\u00e1dio Observador<\/h5><p>Programa As Not\u00edcias das 09.00, dia 1 de abril de 2020.<\/p><p>Programa na \u00edntegra <a href=\"https:\/\/observador.pt\/programas\/noticiario\/as-noticias-das-9h-209\/\">aqui<\/a>.<\/p><h5>Covid \u2013 19 : Instituto de Apoio \u00e0 Crian\u00e7a alerta para elo mais fraco em per\u00edodo de isolamento<\/h5><p>Not\u00edcia e imagem da <a href=\"https:\/\/www.saudemais.tv\/noticia\/10264-covid-19-instituto-de-apoio-a-crianca-alerta-para-elo-mais-fraco-em-periodo-de-isolamento\">Sa\u00fade Mais TV<\/a> de 1 de abril de 2020.<\/p><h5>Capacidade de interven\u00e7\u00e3o em casos de risco de menores est\u00e1 diminu\u00edda<\/h5><p>Declara\u00e7\u00f5es do Dr.\u00b0 Manuel Coutinho, Secret\u00e1rio-Geral do IAC \u00e0 RTP no dia 1 de abril.<\/p><p>Consulte a reportagem <a href=\"https:\/\/www.rtp.pt\/noticias\/pais\/capacidade-de-intervencao-em-casos-de-risco-de-menores-esta-diminuida_v1217347\">aqui<\/a>.<\/p><h5>&#8220;Vizinhos, estejam atentos&#8221; Risco de maus-tratos \u00e0s crian\u00e7as aumenta durante confinamento \u2013 declara\u00e7\u00f5es de Dulce Rocha \u00e0 TSF<\/h5><p>Not\u00edcia da <a href=\"https:\/\/www.tsf.pt\/portugal\/sociedade\/vizinhos-estejam-atentos-risco-de-maus-tratos-as-criancas-aumenta-durante-confinamento-12014342.html\">TSF<\/a> de 1 de abril de 2020<\/p><h5>Linha SOS Crian\u00e7a: &#8220;N\u00e3o h\u00e1 boas maneiras para se dar m\u00e1s not\u00edcias. Nem \u00e0s crian\u00e7as&#8221;<\/h5><p>Entrevista do Dr.\u00b0 Manuel Coutinho, Secret\u00e1rio-Geral do IAC ao <a href=\"https:\/\/24.sapo.pt\/atualidade\/artigos\/linha-sos-crianca-nao-ha-boas-maneiras-para-se-dar-mas-noticias-nem-as-criancas\">Sapo24<\/a> de 2 de abril de 2020.<\/p><h5>Covid-19: IAC- Instituto de Apoio \u00e0 Crian\u00e7a reinventa-se<\/h5><p>Entrevista de Vera Abecasis no dia 2 de Abril, Canal +Sa\u00fade a falar sobre os desafios que estamos a viver atualmente, com a concilia\u00e7\u00e3o trabalho-fam\u00edlia e com a necessidade de nos mantermos alerta para situa\u00e7\u00f5es de maus-tratos que possam ocorrer no seio das fam\u00edlias.<\/p><p>Reveja <a href=\"https:\/\/saudemais.tv\/noticia\/10885-covid-19-iac-instituto-de-apoio-a-crianca-reinventa-se\">aqui<\/a>.<\/p><h5>Confinamento social pode motivar aumento de fuga de menores \u2013 Instituto de Apoio \u00e0 Crian\u00e7a registou duas situa\u00e7\u00f5es de fuga nas \u00faltimas semanas<\/h5><p>Entrevista a Matilde Sirgado do IAC. Not\u00edcia da <a href=\"https:\/\/www.tsf.pt\/portugal\/sociedade\/confinamento-social-pode-motivar-aumento-de-fuga-de-menores-12033169.html\">TSF<\/a> de 5 de abril de 2020.<\/p><h5>SOS-Crian\u00e7a recebeu no primeiro m\u00eas da covid-19 o dobro de chamadas atendidas em tempos normais<\/h5><p>Not\u00edcia do <a href=\"https:\/\/www.publico.pt\/2020\/04\/09\/sociedade\/noticia\/sos-crianca-recebeu-mes-covid19-dobro-chamadas-atendidas-tempos-normais-1911738\">P\u00fablico<\/a> de 9 de abril de 2020.<\/p><h5>Aumenta o n\u00famero de telefonemas para a linha SOS Crian\u00e7a<\/h5><p>Not\u00edcia da <a href=\"https:\/\/www.rtp.pt\/noticias\/mundo\/aumenta-o-numero-de-telefonemas-para-a-linha-sos-crianca_a1220015\">Antena1<\/a> de 11 de abril de 2020<\/p><h5>Peritos juntam-se para ajudar crian\u00e7as e jovens em tempos de pandemia. \u201cTodos somos agentes de protec\u00e7\u00e3o\u201d<\/h5><p>Not\u00edcia do <a href=\"https:\/\/www.publico.pt\/2020\/04\/12\/sociedade\/noticia\/peritos-juntamse-ajudar-criancas-jovens-tempos-pandemia-agentes-proteccao-1911892\">P\u00fablico<\/a> de 12 de abril de 2020<\/p><h5>Tens\u00e3o nas fam\u00edlias aumenta pedidos de ajuda ao SOS Crian\u00e7a<\/h5><p>Not\u00edcia do Jornal de Not\u00edcias de 24 de abril de 2020.<\/p><p>Veja a reportagem <a href=\"https:\/\/criancasatortoeadireitos.wordpress.com\/2020\/04\/24\/tensao-nas-familias-aumenta-pedidos-de-ajuda-ao-sos-crianca\/\">aqui<\/a>.<\/p><h5>Covid-19: jovens em centros educativos tamb\u00e9m v\u00e3o regressar a casa mais cedo \u2013 IAC invoca equidade face aos reclusos adultos<\/h5><p>Reportagem com Matilde Sirgado do IAC, TVI24, 24 de abril.<\/p><p>Reveja <a href=\"https:\/\/tvi24.iol.pt\/videos\/sociedade\/covid-19-jovens-em-centros-educativos-tambem-vao-regressar-a-casa-mais-cedo\/5ea2dbc80cf2c4d7ff3e577b\">aqui<\/a>.<\/p><h5>Instituto de Apoio \u00e0 Crian\u00e7a pede liberta\u00e7\u00e3o de jovens que est\u00e3o em centros educativos<\/h5><p>Entrevista a Matilde Sirgado, Not\u00edcia da <a href=\"https:\/\/www.rtp.pt\/noticias\/pais\/instituto-de-apoio-a-crianca-pede-libertacao-de-jovens-que-estao-em-centros-educativos_v1223466\">RTP<\/a> de 24 de abril de 2020.<\/p><h5>COVID-19 antecipa liberdade de jovens delinquentes \u2013 IAC invoca equidade face aos reclusos adultos<\/h5><p>Not\u00edcia do Jornal de Not\u00edcias de 24 de abril de 2020.<\/p><p>Consulte a not\u00edcia <a href=\"https:\/\/criancasatortoeadireitos.wordpress.com\/2020\/04\/24\/covid-19-antecipa-liberdade-de-jovens-delinquentes-iac-invoca-equidade-face-aos-reclusos-adultos\/\">aqui<\/a>.<\/p><h5>Jovens nos centros educativos tamb\u00e9m devem beneficiar de clem\u00eancia para evitar injusti\u00e7as \u2013 declara\u00e7\u00f5es de Dulce Rocha \u00e0 R\u00e1dio Renascen\u00e7a<\/h5><p>Not\u00edcia da <a href=\"https:\/\/rr.sapo.pt\/2020\/04\/24\/pais\/jovens-nos-centros-educativos-tambem-devem-beneficiar-de-clemencia-para-evitar-injusticas\/noticia\/190474\/\">R\u00e1dio Renascen\u00e7a<\/a> de 24 de abril de 2020.<\/p><h5>Pede clem\u00eancia para jovens<\/h5><p>Not\u00edcia do <a href=\"https:\/\/www.pressreader.com\/portugal\/correio-da-manha\/20200424\/282123523656059\">Correio da Manh\u00e3<\/a> de 24 de abril de 2020<\/p><h5>Treze jovens institucionalizados sa\u00edram antecipadamente<\/h5><p>Not\u00edcia do <a href=\"https:\/\/www.dnoticias.pt\/pais\/treze-jovens-institucionalizados-sairam-antecipadamente-BE6161605\">dnot\u00edcias<\/a> de 24 de abril de 2020.<\/p><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"5\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-9745\" aria-expanded=\"false\">May<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-9745\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-9745\" tabindex=\"0\" hidden=\"hidden\"><h5>\u201cMaioria dos crimes contra crian\u00e7as \u00e9 na fam\u00edlia, mas as pessoas n\u00e3o querem acreditar\u201d, diz Dulce Rocha.<\/h5><p>Not\u00edcia do R\u00e1dio Observador de 10 de maio de 2020.<\/p><p>Not\u00edcia <a href=\"https:\/\/observador.pt\/programas\/resposta-pronta\/as-comissoes-nao-sao-adivinhas-mas-podem-ser-treinadas-para-evitar-casos-destes-diz-dulce-rocha\/?fbclid=IwAR1UtV5fNVCXc6YX0-3CyDNXOgTGYj4NGs1yaTbUq0_jHizmmIxJVoAcDIs\">aqui<\/a>.<\/p><h5>Por tr\u00e1s de uma fuga h\u00e1 sempre uma hist\u00f3ria triste de uma crian\u00e7a \u2013 Entrevista de Dulce Rocha e Matilde Sirgado na RTP<\/h5><p>Reportagem do Telejornal da RTP de 11 de maio de 2020.<\/p><p>Reportagem <a href=\"https:\/\/www.youtube.com\/redirect?event=video_description&amp;v=pLa2L84beL0&amp;q=https%3A%2F%2Fwww.rtp.pt%2Fplay%2Fp6559%2Ftelejornal&amp;redir_token=8otA92Tf-O-f0ZB7ZNJJmsRAYyB8MTU4OTM2NTIyMkAxNTg5Mjc4ODIy\">aqui<\/a>.<\/p><h5>O caso Valentina em an\u00e1lise na SIC Not\u00edcias com a participa\u00e7\u00e3o de Dulce Rocha<\/h5><p>SIC Not\u00edcias de 11 de maio de 2020.<\/p><p>A Dra. Dulce Rocha participou nos minutos 07:08 \u2013 13:50 e 26:54m \u2013 30:05<\/p><p>V\u00eddeo <a href=\"https:\/\/sicnoticias.pt\/pais\/2020-05-11-O-caso-Valentina-em-analise?fbclid=IwAR2OOgUYDb5NKNTZBgb-eo7paxceEShTpIrsn4i7-e2jAb9ID7gMOo8-tT8\">aqui<\/a>.<\/p><h5>Guarda partilhada pode n\u00e3o ser a op\u00e7\u00e3o ideal para algumas crian\u00e7as \u2013 Entrevista de Manuel Coutinho \u00e0 RTP<\/h5><p>Entrevista de Manuel Coutinho \u00e0 RTP no dia 11 de maio de 2020.<\/p><p>Entrevista <a href=\"https:\/\/www.rtp.pt\/noticias\/pais\/guarda-partilhada-pode-nao-ser-a-opcao-ideal-para-algumas-criancas_v1227771\">aqui<\/a>.<\/p><h5>Entrevista de Matilde Sirgado do IAC sobre o caso Valentina<\/h5><p>Entrevista Matilde Sirgado \u00e0 RTP3 no dia 11 de maio de 2020.<\/p><p>Entrevista <a href=\"https:\/\/www.youtube.com\/watch?v=7Dgdn2aBmXA&amp;t=3s\">aqui<\/a>.<\/p><h5>Valentina: \u201cJ\u00e1 se devia ter ouvido a crian\u00e7a com muita aten\u00e7\u00e3o. E a m\u00e3e\u201d Entrevista de Dulce Rocha na TVI<\/h5><p>TVI \u2013 Jornal das 8, no dia 13 de maio de 2020.<\/p><p>V\u00eddeo <a href=\"https:\/\/tvi24.iol.pt\/videos\/sociedade\/valentina-ja-se-devia-ter-ouvido-a-crianca-com-muita-atencao-e-a-mae\/5ebc71330cf2cd6069ebef10\">aqui<\/a>.<\/p><h5>Participa\u00e7\u00e3o de Dulce Rocha, no programa \u201cA Tarde \u00e9 Sua\u201d na TVI<\/h5><p>TVI 14 de maio de 2020.<\/p><p>A Dra. Dulce Rocha participou no programa entre os minutos 1.03.50.m \u2013 1.22.40m<\/p><p>V\u00eddeo <a href=\"https:\/\/tviplayer.iol.pt\/programa\/a-tarde-e-sua\/53c6b3883004dc006243ce59\/video\/5ebd7daf0cf2cd6069ebf3b6\">aqui<\/a>.<\/p><h5>Confinamento fez disparar chamadas para o SOS-Crian\u00e7a e desconfinamento pode fazer o mesmo: \u201cMuitas pessoas est\u00e3o com fobia da normalidade\u201d<\/h5><p>Not\u00edcia do <a href=\"https:\/\/expresso.pt\/coronavirus\/2020-05-14-Confinamento-fez-disparar-chamadas-para-o-SOS-Crianca-e-desconfinamento-pode-fazer-o-mesmo-Muitas-pessoas-estao-com-fobia-da-normalidade\">Expresso<\/a> de 14 de maio de 2020 com declara\u00e7\u00f5es do Manuel Coutinho.<\/p><h5>O caso Valentina em an\u00e1lise na CM TV com a participa\u00e7\u00e3o de Matilde Sirgado<\/h5><p>Matilde Sirgado esteve em direto via Skype num programa sobre o caso Valentina com Rui Pereira, T\u00e2nia Laranjo e Fel\u00edcia Cabrita no dia 16 de maio de 2020.<\/p><p>V\u00eddeo do programa <a href=\"https:\/\/www.cmjornal.pt\/multimedia\/videos\/detalhe\/valentina-foi-sinalizada-pela-cpcj-em-2019-mas-o-caso-foi-arquivado-em-apenas-um-mes\">aqui<\/a>.<\/p><h5>Confinamento leva ao aumento de contactos para a Linha SOS Crian\u00e7a<\/h5><p>Not\u00edcia do i de 19 de maio de 2020 com declara\u00e7\u00f5es de Manuel Coutinho.<\/p><p>Visualizar a not\u00edcia <a href=\"https:\/\/criancasatortoeadireitos.wordpress.com\/2020\/05\/19\/confinamento-leva-ao-aumento-de-contactos-para-a-linha-sos-crianca\/\">aqui<\/a>.<\/p><h5>Crian\u00e7as em confinamento pedem mais aux\u00edlio \u2013 not\u00edcia com declara\u00e7\u00f5es de Manuel Coutinho do IAC<\/h5><p>Not\u00edcia do Jornal de Not\u00edcias de 19 de maio de 2020<\/p><p>Visualizar a not\u00edcia <a href=\"https:\/\/criancasatortoeadireitos.wordpress.com\/2020\/05\/19\/criancas-em-confinamento-pedem-mais-auxilio-noticia-do-jn-com-declaracoes-de-manuel-coutinho-do-iac\/\">aqui<\/a>.<\/p><h5>Linha SOS Crian\u00e7a: \u201cPais n\u00e3o conseguiram conter ansiedade dos filhos em rela\u00e7\u00e3o \u00e0 Covid-19\u201d Entrevista de Manuel Coutinho <\/h5><p>Entrevista de 19 de maio de 2020 da R\u00e1dio Observador <a href=\"https:\/\/criancasatortoeadireitos.wordpress.com\/2020\/05\/19\/linha-sos-crianca-pais-nao-conseguiram-conter-ansiedade-dos-filhos-em-relacao-a-covid-19-entrevista-de-manuel-coutinho-do-iac-a-radio-observador\/\">aqui<\/a>.<\/p><h5>Instituto da Crian\u00e7a quer alterar pena do crime de viola\u00e7\u00e3o &#8211; not\u00edcia com declara\u00e7\u00f5es de Manuela Eanes<\/h5><p>Not\u00edcia do <a href=\"https:\/\/criancasatortoeadireitos.wordpress.com\/2020\/05\/21\/instituto-da-crianca-quer-alterar-pena-do-crime-de-violacao\/\">Jornal de Not\u00edcias<\/a> de 21 de maio de 2020.<\/p><h5>Linha SOS Crian\u00e7a registou este ano 10 casos de crian\u00e7as desaparecidas &#8211; not\u00edcia com declara\u00e7\u00f5es de Maria Jo\u00e3o Cosme <\/h5><p>Not\u00edcia da <a href=\"https:\/\/criancasatortoeadireitos.wordpress.com\/2020\/05\/26\/linha-sos-crianca-registou-este-ano-10-casos-de-criancas-desaparecidas\/\">S\u00e1bado<\/a> de 26 de maio de 2020.<\/p><h5>#MovimentoViverIntensamente quer devolver o recreio \u00e0s crian\u00e7as \u2013 not\u00edcia com declara\u00e7\u00f5es de Melanie Tavares<\/h5><p>Not\u00edcia do <a href=\"https:\/\/criancasatortoeadireitos.wordpress.com\/2020\/05\/28\/movimentoviverintensamente-quer-devolver-o-recreio-as-criancas-noticia-com-declaracoes-de-melanie-tavares-do-iac\/\">Sapo Lifestyle<\/a> de 27 de maio de 2020.<\/p><h5>Cruel realidade &#8211; artigo de opini\u00e3o de Manuela Eanes<\/h5><p>Artigo de opini\u00e3o publicado no <a href=\"https:\/\/criancasatortoeadireitos.wordpress.com\/2020\/05\/29\/cruel-realidade\/\">Jornal de Not\u00edcias<\/a> de 28 de maio de 2020.<\/p><h5>Crian\u00e7as espelham os medos dos pais \u2013 entrevista de Manuel Coutinho<\/h5><p>Visualizar a entrevista do Jornal de Not\u00edcias de 29 de maio de 2020 <a href=\"https:\/\/criancasatortoeadireitos.wordpress.com\/2020\/05\/29\/criancas-espelham-os-medos-dos-pais-entrevista-de-manuel-coutinho-do-iac-ao-jn\/\">aqui<\/a>.<\/p><h5>Entrevista de Matilde Sirgado na RDP Internacional<\/h5><p>Programa Clube da Amizade, 31 de maio de 2020 sobre o Dia Mundial da Crian\u00e7a.<\/p><p>Ouvir o programa <a href=\"https:\/\/criancasatortoeadireitos.wordpress.com\/2020\/06\/05\/entrevista-de-matilde-sirgado-do-iac-na-rdp-internacional-clube-da-amizade\/\">aqui<\/a>.<\/p><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"6\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-9746\" aria-expanded=\"false\">June<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-9746\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"6\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-9746\" tabindex=\"0\" hidden=\"hidden\"><h5>Entrevista de Manuel Coutinho do IAC \u00e0 R\u00e1dio Mi\u00fados no Dia Mundial da Crian\u00e7a<\/h5><p>Entrevista <a href=\"https:\/\/www.radiomiudos.pt\/index.php?id=2145\">aqui<\/a>.<\/p><h5>Peti\u00e7\u00e3o pede estatuto de v\u00edtima para crian\u00e7as expostas \u00e0 viol\u00eancia dom\u00e9stica \u2013 Not\u00edcia com declara\u00e7\u00f5es da Presidente do IAC Dulce Rocha<\/h5><p>Not\u00edcia da <a href=\"https:\/\/radiocomercial.iol.pt\/noticias\/100812\/peticao-pede-estatuto-de-vitima-para-criancas-expostas-a-violencia-domestica\">R\u00e1dio Comercial<\/a> de 1 de junho de 2020<\/p><h5>Peti\u00e7\u00e3o prop\u00f5e estatuto de v\u00edtima para crian\u00e7as expostas \u00e0 viol\u00eancia dom\u00e9stica<\/h5><p>Not\u00edcia da <a href=\"https:\/\/www.tsf.pt\/portugal\/sociedade\/peticao-propoe-estatuto-de-vitima-para-criancas-expostas-a-violencia-domestica-12263322.html\">TSF<\/a> de 1 de junho de 2020.<\/p><h5>Entrevista de Manuel Coutinho do IAC na RTP1 Portugal em Direto<\/h5><p>4 de junho de 2020. V\u00eddeo <a href=\"https:\/\/criancasatortoeadireitos.wordpress.com\/2020\/06\/05\/entrevista-de-manuel-coutinho-do-iac-na-rtp1-portugal-em-direto\/\">aqui<\/a>.<\/p><h5>Covid:19 &#8211; \u201cO empobrecimento vai refletir-se em pobreza infantil\u201d, alerta Presidente do Instituto de Apoio \u00e0 Crian\u00e7a<\/h5><p>Not\u00edcia do <a href=\"https:\/\/www.saudemais.tv\/noticia\/19969-covid-19-o-empobrecimento-vai-refletir-se-em-pobreza-infantil-alerta-presidente-executiva-do-instituto-de-apoio-a-crianca?fbclid=IwAR0fDmoObduAaYvYMIqFB3v-F1gYvzk98xt4CKJfCpq2pCjBsyi6_1y4PF0\">Canal Sa\u00fade+<\/a> de 12 de junho de 2020.<\/p><h5>#MovimentoViverIntensamente \u2013 Entrevista de Melanie Tavares do IAC na TSF<\/h5><p><a href=\"https:\/\/www.tsf.pt\/programa\/tsf-pais-e-filhos.html\">TSF Pais e Filhos<\/a> de 18 de junho de 2020. Ouvir o programa <a href=\"http:\/\/pt.cision.com\/cp2013\/ClippingDetails.aspx?id=047f0a76-939a-4da0-8143-90027f7c1f16&amp;userId=02355b15-4dd6-4427-8cc3-fd458c5ed248&amp;userid=02355b15-4dd6-4427-8cc3-fd458c5ed248\">aqui<\/a>.<\/p><h5>Pandemia trava bullying nas escolas, mas PSP ainda registou 115 casos \u2013 Not\u00edcia do DN com declara\u00e7\u00f5es de Melanie Tavares do IAC<\/h5><p>Not\u00edcia do <a href=\"https:\/\/criancasatortoeadireitos.wordpress.com\/2020\/06\/23\/pandemia-trava-bullying-nas-escolas-mas-psp-ainda-registou-115-casos-noticia-do-dn-com-declaracoes-de-melanie-tavares-do-iac\/\">Di\u00e1rio de Not\u00edcias<\/a> de 20 de junho de 2020.<\/p><h5>Aos olhos de uma crian\u00e7a, uma caixa pode transformar-se num pal\u00e1cio \u2013 Melanie Tavares do IAC na TSF<\/h5><p>Not\u00edcia da <a href=\"https:\/\/www.tsf.pt\/programa\/tsf-pais-e-filhos\/aos-olhos-de-uma-crianca-uma-caixa-pode-transformar-se-num-palacio-12351599.html\">TSF<\/a> de 25 de junho de 2020.<\/p><h5>Prote\u00e7\u00e3o de menores. Regresso \u00e0 escola \u00e9 essencial para combater desigualdades e proteger crian\u00e7as em risco<\/h5><p>Not\u00edcia do <a href=\"https:\/\/criancasatortoeadireitos.wordpress.com\/2020\/07\/06\/protecao-de-menores-regresso-a-escola-e-essencial-para-combater-desigualdades-e-proteger-criancas-em-risco-noticia-com-declaracoes-de-dulce-rocha-do-iac\/\">Observador<\/a> de 30 de junho de 2020 com declara\u00e7\u00f5es de Dulce Rocha e Matilde Sirgado do IAC.<\/p><h5>Audi\u00e7\u00e3o Parlamentar de Dulce Rocha e de Matilde Sirgado na Comiss\u00e3o de Trabalho e Seguran\u00e7a Social da Assembleia da Rep\u00fablica<\/h5><p>Dia 30 de junho de 2020 na Comiss\u00e3o de Trabalho e Seguran\u00e7a Social da Assembleia da Rep\u00fablica. V\u00eddeo <a href=\"https:\/\/canal.parlamento.pt\/?cid=4658&amp;title=audicao-de-dulce-rocha-e-de-matilde-sirgado\">aqui<\/a>.<\/p><h5>Em Mem\u00f3ria de Valentina\u2026 Texto de Ana Perdig\u00e3o do IAC<\/h5><p>Texto de Ana Perdig\u00e3o do IAC publicado na revista <a href=\"https:\/\/www.fatimamissionaria.pt\/48824\/junho-2020\/?fbclid=IwAR2ux60A6xI7dLGQYwGBD585cmW9xa9suMoXVGa_Xk0HlGiHqTLuaCj-DrE\">F\u00e1tima Mission\u00e1ria<\/a>.- n. 6 (jun. 2020), p. 5<\/p><h5>Instituto de Apoio \u00e0 Crian\u00e7a \u2013 Artigo de Melanie Tavares do IAC<\/h5><p><a href=\"https:\/\/criancasatortoeadireitos.wordpress.com\/2020\/06\/19\/instituto-de-apoio-a-crianca-artigo-de-melanie-tavares-do-iac-na-revista-desenvolvescer-reflexoes-sobre-a-infancia-e-a-familia\/\">Desenvolvescer \u2013 Reflex\u00f5es sobre a inf\u00e2ncia e a fam\u00edlia<\/a>.- n. 3 (jun. 2020), p. 27-28<\/p><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"7\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-9747\" aria-expanded=\"false\">July<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-9747\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"7\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-9747\" tabindex=\"0\" hidden=\"hidden\"><h5><strong>Aumentam os pedidos de ajuda \u00e0 Linha SOS Crian\u00e7a<\/strong><\/h5><p>Not\u00edcia do <a href=\"https:\/\/criancasatortoeadireitos.wordpress.com\/2020\/07\/13\/aumentam-os-pedidos-de-ajuda-a-linha-sos-crianca-2\/\" target=\"_blank\" rel=\"noopener\">Jornal de Not\u00edcias<\/a> de 11 de julho com declara\u00e7\u00f5es de Manuel Coutinho.<\/p><h5><strong>Linha SOS Crian\u00e7a &#8211; Pedidos de ajuda dispararam durante a pandemia<\/strong> <\/h5><p>Entrevista de Manuel Coutinho \u00e0 SIC Not\u00edcias no dia 12 de julho. V\u00eddeo <a href=\"https:\/\/www.youtube.com\/watch?v=GCVrxVLWjI0&amp;feature=emb_logo\" target=\"_blank\" rel=\"noopener\">aqui<\/a><\/p><h5><strong>(Re)descubra 5 jogos em fam\u00edlia para fazer na praia em tempos de pandemia<\/strong><\/h5><p>Not\u00edcia do <a href=\"https:\/\/www.noticiasdecoimbra.pt\/redescubra-5-jogos-em-familia-para-fazer-na-praia-em-tempos-de-pandemia\/\" target=\"_blank\" rel=\"noopener\">Not\u00edcias de Coimbra<\/a> de 13 de julho com declara\u00e7\u00f5es de Melanie Tavares.<\/p><h5><strong>Programa Estou Aqui! Est\u00e1 de regresso<\/strong><\/h5><p>Not\u00edcia do <a href=\"https:\/\/criancasatortoeadireitos.wordpress.com\/2020\/07\/16\/programa-estou-aqui-esta-de-regresso\/\" target=\"_blank\" rel=\"noopener\">Sol <\/a>de 14 de julho.<br>O Programa \u201c<a href=\"https:\/\/estouaqui.mai.gov.pt\/Pages\/Home.htm\" target=\"_blank\" rel=\"noopener\">Estou aqui<\/a>\u201d 2020 da PSP, que tem como parceiros o Instituto de Apoio \u00e0 Crian\u00e7a, Missing Children Europe, SGMAI, Altice, MEO, R\u00e1dio Comercial j\u00e1 se encontra ativo.<\/p><h5><strong>MAI avan\u00e7a com apoio de mais de 200 mil euros \u00e0 APAV e ao Instituto de Apoio \u00e0 Crian\u00e7a.<\/strong><\/h5><p>Not\u00edcia do <a href=\"https:\/\/criancasatortoeadireitos.wordpress.com\/2020\/07\/16\/mai-avanca-com-apoio-de-mais-de-200-mil-euros-a-apav-e-ao-instituto-de-apoio-a-crianca\/\" target=\"_blank\" rel=\"noopener\">Sapo 24<\/a> de 15 de julho.<\/p><h5><strong>Crian\u00e7as est\u00e3o mais preocupadas com a sa\u00fade, sobretudo com a dos av\u00f3s<\/strong><\/h5><p>Not\u00edcia da <a href=\"https:\/\/criancasatortoeadireitos.wordpress.com\/2020\/07\/15\/criancas-estao-mais-preocupadas-com-a-saude-sobretudo-com-a-dos-avos-noticia-da-tsf-sobre-estudo-do-iac\/\" target=\"_blank\" rel=\"noopener\">TSF<\/a> de 15 de julho com declara\u00e7\u00f5es de Fernanda Salvaterra.<\/p><h5><strong>O que mais preocupa as crian\u00e7as na pandemia \u00e9 a sa\u00fade dos av\u00f3s<\/strong><\/h5><p>Not\u00edcia do <a href=\"https:\/\/criancasatortoeadireitos.wordpress.com\/2020\/07\/15\/o-que-mais-preocupa-as-criancas-na-pandemia-e-a-saude-dos-avos-noticia-do-publico-sobre-estudo-do-iac\/\" target=\"_blank\" rel=\"noopener\">P\u00fablico<\/a> de 15 de julho com declara\u00e7\u00f5es de Fernanda Salvaterra.<\/p><h5><strong>Mais de 45 mil reclamam estatuto de v\u00edtima para crian\u00e7as<\/strong><\/h5><p>Not\u00edcia do <a href=\"https:\/\/criancasatortoeadireitos.wordpress.com\/2020\/07\/22\/mais-de-45-mil-reclamam-estatuto-de-vitima-para-criancas-noticia-com-declaracoes-de-dulce-rocha-presidente-do-iac\/\" target=\"_blank\" rel=\"noopener\">P\u00fablico<\/a> de 22 de julho de 2020 com declara\u00e7\u00f5es de Dulce Rocha.<\/p><h5><strong>Mulher v\u00edtima. Crian\u00e7a v\u00edtima<\/strong><\/h5><p>Artigo de opini\u00e3o de Manuela Eanes, publicado no <a href=\"https:\/\/criancasatortoeadireitos.wordpress.com\/2020\/07\/22\/mulher-vitima-crianca-vitima-artigo-de-opiniao-de-manuela-eanes-presidente-honoraria-do-iac\/\" target=\"_blank\" rel=\"noopener\">P\u00fablico<\/a> de 22 de julho.<\/p><h5><strong>Entregue peti\u00e7\u00e3o que exige \u201cestatuto legal de v\u00edtima\u201d para crian\u00e7as que presenciaram viol\u00eancia dom\u00e9stica<\/strong><\/h5><p>Not\u00edcia da <a href=\"https:\/\/tvi24.iol.pt\/videos\/sociedade\/entregue-peticao-que-exige-estatuto-legal-de-vitima-para-criancas-que-presenciaram-violencia-domestica\/5f1839e10cf2b3ce9d342e11\" target=\"_blank\" rel=\"noopener\">TVI24<\/a> de 22 de julho com declara\u00e7\u00f5es de Dulce Rocha.<\/p><h5><strong>Estatuto de v\u00edtima de viol\u00eancia para crian\u00e7as. Peti\u00e7\u00e3o exige prote\u00e7\u00e3o quando assistem a agress\u00f5es em casa<\/strong><\/h5><p>Not\u00edcia da <a href=\"https:\/\/sicnoticias.pt\/pais\/2020-07-22-Estatuto-de-vitima-de-violencia-para-criancas.-Peticao-exige-protecao-quando-assistem-a-agressoes-em-casa\" target=\"_blank\" rel=\"noopener\">SIC Not\u00edcias<\/a> de 22 de julho com declara\u00e7\u00f5es de Dulce Rocha.<\/p><h5><strong>Crian\u00e7as devem estar protegidas pela lei<\/strong><\/h5><p>Entrevista de Dulce Rocha, ao <a href=\"https:\/\/criancasatortoeadireitos.wordpress.com\/2020\/08\/04\/criancas-devem-estar-protegidas-pela-lei-entrevista-de-dulce-rocha-presidente-do-iac-ao-correio-da-manha\/\" target=\"_blank\" rel=\"noopener\">Correio da Manh\u00e3 <\/a>de 23 de julho.<\/p><h5><strong>Medo de contagiar os av\u00f3s foi <\/strong><strong>preocupa\u00e7\u00e3o<\/strong><strong> das crian\u00e7as na pandemia <\/strong> <\/h5><p>Not\u00edcia do <a href=\"https:\/\/criancasatortoeadireitos.wordpress.com\/2020\/08\/03\/medo-de-contagiar-os-avos-foi-preocupacao-das-criancas-na-pandemia-noticia-do-jn-sobre-um-estudo-do-iac\/\" target=\"_blank\" rel=\"noopener\">Jornal de Not\u00edcias<\/a> de 26 de julho.<br>A not\u00edcia menciona o estudo do IAC <strong>\u201c<\/strong>O Que Pensam e o Que Sentem as Fam\u00edlias em Isolamento Social\u201d.<\/p><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"8\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-9748\" aria-expanded=\"false\">August<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-9748\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"8\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-9748\" tabindex=\"0\" hidden=\"hidden\"><h5><strong>Crian\u00e7a negra &#8220;cartaz&#8221; em manifesta\u00e7\u00e3o do Chega<\/strong><\/h5><p>Not\u00edcia de 7 de agosto do <a href=\"https:\/\/www.dn.pt\/edicao-do-dia\/07-ago-2020\/crianca-negra-cartaz-em-manifestacao-do-chega-12502908.html\" target=\"_blank\" rel=\"noopener\">Di\u00e1rio de Not\u00edcias<\/a> com declara\u00e7\u00f5es de Dulce Rocha.<\/p><h5><strong>Crian\u00e7as continuam a ser obrigadas a visitar agressores<\/strong><\/h5><p>Participa\u00e7\u00e3o de Dulce Rocha no programa \u201cA Tarde \u00e9 Sua\u201d na TVI de 24 de agosto de 2020.<\/p><p>Visualizar o programa entre os minutos 33.15 m \u2013 43.30 m <a href=\"https:\/\/tviplayer.iol.pt\/programa\/a-tarde-e-sua\/53c6b3883004dc006243ce59\/video\/5f43f67a0cf2e21cf3317325\" target=\"_blank\" rel=\"noopener\">aqui<\/a><\/p><h5><strong>&#8220;Para crian\u00e7as de tenra idade, isto \u00e9 o quarto escuro. Parece que cometeram um crime&#8221;<\/strong> <\/h5><p>Not\u00edcia do <a href=\"https:\/\/criancasatortoeadireitos.wordpress.com\/2020\/08\/28\/para-criancas-de-tenra-idade-isto-e-um-quarto-escuro-parece-que-cometeram-um-crime-noticia-do-publico-com-declaracoes-de-ana-perdigao-do-iac\/\" target=\"_blank\" rel=\"noopener\">P\u00fablico<\/a> de 28 de agosto com declara\u00e7\u00f5es de Ana Perdig\u00e3o. <\/p><h5><strong>\u201cN\u00e3o fazemos isso aos ingleses\u201d que chegam a Portugal. Isolamento de crian\u00e7as \u00e9 \u201cdram\u00e1tico\u201d<\/strong><\/h5><p>Declara\u00e7\u00f5es de Dulce Rocha \u00e0 <a href=\"https:\/\/criancasatortoeadireitos.wordpress.com\/2020\/08\/28\/nao-fazemos-isso-aos-ingleses-que-chegam-a-portugal-isolamento-de-criancas-e-dramatico-declaracoes-de-dulce-rocha-presidente-do-iac-a-tsf\/\" target=\"_blank\" rel=\"noopener\">TSF<\/a> no dia 28 de agosto.<\/p><h5><strong>Comunicado da Dire\u00e7\u00e3o<\/strong><\/h5><p>A prop\u00f3sito da obrigatoriedade da disciplina de Cidadania e Desenvolvimento. Pode ler documento <a href=\"https:\/\/bit.ly\/3itazJ7\" target=\"_blank\" rel=\"noopener\">aqui<\/a>.<\/p><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"9\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-9749\" aria-expanded=\"false\">September<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-9749\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"9\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-9749\" tabindex=\"0\" hidden=\"hidden\"><h5><strong>DGS recua e acaba com isolamento obrigat\u00f3rio de crian\u00e7as em casas de acolhimento, IAC aplaude.<\/strong><\/h5><p>Not\u00edcia do <a href=\"https:\/\/www.publico.pt\/2020\/09\/04\/sociedade\/noticia\/dgs-recua-acaba-isolamento-obrigatorio-criancas-casas-acolhimento-1930390\" target=\"_blank\" rel=\"noopener\">P\u00fablico<\/a> de 4 de setembro com declara\u00e7\u00f5es de Ana Perdig\u00e3o.<\/p><h5><strong>Comunicado da Dire\u00e7\u00e3o<\/strong><\/h5><p>A prop\u00f3sito da obrigatoriedade da disciplina de Cidadania e Desenvolvimento. Pode ler documento <a href=\"https:\/\/bit.ly\/3itazJ7\" target=\"_blank\" rel=\"noopener\">aqui<\/a>.<\/p><h5 id=\"post-60120\"><strong>Testar e errar : mais vale assumir riscos no regresso \u00e0s aulas<\/strong><\/h5><p>Not\u00edcia do <a href=\"https:\/\/criancasatortoeadireitos.wordpress.com\/2020\/10\/07\/testar-e-errar-mais-vale-assumir-riscos-no-regresso-as-aulas-noticia-declaracoes-de-manuel-coutinho-do-iac\/\" target=\"_blank\" rel=\"noopener\">Jornal de Not\u00edcias<\/a> de 10 de setembro com declara\u00e7\u00f5es de Manuel Coutinho.<\/p><h5><strong>Instituto de Apoio \u00e0 Crian\u00e7a defende obrigatoriedade de disciplina de cidadania<\/strong><\/h5><p>Not\u00edcia da <a href=\"https:\/\/tvi24.iol.pt\/sociedade\/criancas\/instituto-de-apoio-a-crianca-defende-obrigatoriedade-de-disciplina-de-cidadania\" target=\"_blank\" rel=\"noopener\">TVI24<\/a> de 14 de setembro.<\/p><h5><strong>Organiza\u00e7\u00f5es apoiam em carta aberta ju\u00edza que comentou caso Valentina no Facebook<\/strong><\/h5><p>Not\u00edcia do <a href=\"https:\/\/observador.pt\/2020\/09\/25\/organizacoes-apoiam-em-carta-aberta-juiza-que-comentou-caso-valentina-no-facebook\/\" target=\"_blank\" rel=\"noopener\">Observador<\/a> de 25 de setembro.<\/p><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"10\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-97410\" aria-expanded=\"false\">October<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-97410\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"10\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-97410\" tabindex=\"0\" hidden=\"hidden\"><h5><strong>\u201cSinto que nos unimos em prol das crian\u00e7as portuguesas\u201d<\/strong><\/h5><p>Not\u00edcia do <a href=\"https:\/\/criancasatortoeadireitos.wordpress.com\/2020\/10\/19\/sinto-que-nos-unimos-em-prol-das-criancas-portuguesas\/\" target=\"_blank\" rel=\"noopener\">Sol<\/a> de 16 de outubro, Manuela Eanes (Presidente Honor\u00e1ria do IAC) e Dulce Rocha (Presidente do IAC) s\u00e3o mencionadas na not\u00edcia.<\/p><h5 id=\"post-60120\"><strong>Pandemia leva mais crian\u00e7as a pedir ajuda<\/strong><\/h5><p>Not\u00edcia do<a href=\"https:\/\/criancasatortoeadireitos.wordpress.com\/2020\/10\/16\/pandemia-leva-mais-criancas-a-pedir-ajuda-noticia-do-cm-com-declaracoes-de-manuel-coutinho-do-iac\/\" target=\"_blank\" rel=\"noopener\"> Correio da Manh\u00e3<\/a> de 16 de outubro com declara\u00e7\u00f5es de Manuel Coutinho.<\/p><h5><strong>Programa &#8220;Em Foco&#8221;<\/strong><\/h5><p>Participa\u00e7\u00e3o de Matilde Sirgado, no Programa &#8220;Em Foco&#8221;, no dia 9 de Outubro de 2020, na RTP \u00c1frica. <br>Reveja a interven\u00e7\u00e3o <a href=\"https:\/\/www.youtube.com\/watch?v=3zk-k_7Db3g\" target=\"_blank\" rel=\"noopener\">aqui <\/a> <\/p><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"11\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-97411\" aria-expanded=\"false\">November<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-97411\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"11\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-97411\" tabindex=\"0\" hidden=\"hidden\"><p><strong>Caso Santiago<\/strong><\/p><p>Participa\u00e7\u00e3o de Paula Duarte, Coordenadora do IAC- Coimbra no <a href=\"https:\/\/www.youtube.com\/watch?v=xd0z3--rF1A\" target=\"_blank\" rel=\"noopener\">Programa Pra\u00e7a da Alegria <\/a>da RTP1 no dia 17 de novembro.<\/p><p> <\/p><p><strong>Selo Escola Amiga da Crian\u00e7a para Alvai\u00e1zere<\/strong><\/p><p>Not\u00edcia do <a href=\"https:\/\/criancasatortoeadireitos.wordpress.com\/2020\/12\/04\/selo-escola-amiga-da-crianca-para-alvaiazere\/\" target=\"_blank\" rel=\"noopener\">Di\u00e1rio de Coimbra<\/a> de 25 de novembro de 2020.<\/p><p id=\"post-60120\"><strong>Cyberbullying : &#8220;As pessoas t\u00eam um sentimento de impunidade&#8221; nas redes sociais.<\/strong><\/p><p>Participa\u00e7\u00e3o de Dulce Rocha no programa da TVI24 <a href=\"https:\/\/www.youtube.com\/watch?v=JEPndl5klqo\" target=\"_blank\" rel=\"noopener\">&#8220;Cyberbullying em debate&#8221;<\/a> no dia 28 de novembro de 2020.<\/p><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"12\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-97412\" aria-expanded=\"false\">December<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-97412\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"12\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-97412\" tabindex=\"0\" hidden=\"hidden\"><p><span style=\"font-family: lato, helvetica neue, helvetica, arial, sans-serif;\"><strong>Fam\u00edlias<\/strong><strong> e filhos adoptivos v\u00e3o ter uma linha de apoio gratuita e confidencial<\/strong><\/span><\/p><p><span style=\"font-family: lato, helvetica neue, helvetica, arial, sans-serif;\">Not\u00edcia do <a href=\"https:\/\/criancasatortoeadireitos.wordpress.com\/2020\/12\/16\/familias-e-filhos-adoptivos-vao-ter-uma-linha-de-apoio-gratuita-e-confidencial-linha-lancada-pelo-instituto-de-apoio-a-crianca\/\" target=\"_blank\" rel=\"noopener\">P\u00fablico<\/a> de 16 de dezembro sobre a Linha SOS Fam\u00edlia-Ado\u00e7\u00e3o do IAC.<\/span><\/p><p> <\/p><p><strong>Nova Linha SOS Fam\u00edlia-Ado\u00e7\u00e3o<\/strong><\/p><p>Not\u00edcia do Jornal da Uma da TVI de 16 de Dezembro. V\u00eddeo da entrevista de Fernanda Salvaterra <a href=\"https:\/\/www.youtube.com\/watch?v=YQ8qxeS-hMw\" target=\"_blank\" rel=\"noopener\">aqui<\/a><\/p><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-00edf2c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"00edf2c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8d6cf9a\" data-id=\"8d6cf9a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dce1000 elementor-widget elementor-widget-heading\" data-id=\"dce1000\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-large\">2019<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7ed030a elementor-tabs-view-vertical elementor-widget elementor-widget-tabs\" data-id=\"7ed030a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1321\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1321\" aria-expanded=\"false\">December<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1322\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1322\" aria-expanded=\"false\">November<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1321\" aria-expanded=\"false\">December<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1321\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1321\" tabindex=\"0\" hidden=\"false\"><h5>Em m\u00e9dia 1.400 crian\u00e7as s\u00e3o dadas como desaparecidas todos os anos em Portugal<\/h5><p>Not\u00edcia com declara\u00e7\u00f5es de Dulce Rocha Presidente do IAC \u00e0 SIC Not\u00edcias no dia 4 de dezembro.<\/p><p>Link do v\u00eddeo: <a href=\"http:\/\/bit.do\/fnHvF\">http:\/\/bit.do\/fnHvF<\/a><\/p><h5>Atrav\u00e9s da Conven\u00e7\u00e3o h\u00e1 uma altera\u00e7\u00e3o do paradigma<\/h5><p>Entrevista de Manuel Coutinho, Secret\u00e1rio-Geral do IAC \u00e0 revista Escola Informa\u00e7\u00e3o Digital n.\u00ba 23, dez. 2019, p\u00e1g. 17-20.<\/p><p>Ler a entrevista no link: <a href=\"http:\/\/bit.do\/fnHtP\">http:\/\/bit.do\/fnHtP<\/a><\/p><h5>O problema est\u00e1 na coopera\u00e7\u00e3o deficiente<\/h5><p>Entrevista de Dulce Rocha Presidente do IAC ao <a href=\"https:\/\/criancasatortoeadireitos.wordpress.com\/2019\/12\/11\/o-problema-esta-na-cooperacao-deficiente-dulce-rocha-presidente-do-iac-ao-correio-da-manha\/\">Correio da Manh\u00e3<\/a> de 5 de dezembro.<\/p><h5>Apresenta\u00e7\u00e3o dos Guias Amplos<\/h5><p>Participa\u00e7\u00e3o de Vera Abecasis do IAC Humaniza\u00e7\u00e3o no programa Anatomia de V\u00e9nus, Canal Sa\u00fade + &#8211; no dia 13 de dezembro.<\/p><p>Link do programa: <a href=\"http:\/\/bit.do\/fnNya\">http:\/\/bit.do\/fnNya<\/a><\/p><h5>Resid\u00eancia alternada pode ter &#8220;consequ\u00eancias muito danosas&#8221; para os &#8220;mais vulner\u00e1veis&#8221;<\/h5><p>Participa\u00e7\u00e3o de Dulce Rocha Presidente do IAC na TVI24 no dia 14 de dezembro.<\/p><p>Link do v\u00eddeo: <a href=\"http:\/\/bit.do\/fnHJY\">http:\/\/bit.do\/fnHJY<\/a><\/p><h5>Menores na rua s\u00e3o pouco comuns em Portugal<\/h5><p>Not\u00edcia do <a href=\"https:\/\/criancasatortoeadireitos.wordpress.com\/2020\/01\/07\/menores-na-rua-sao-pouco-comuns-em-portugal-dados-estatisticos-do-iac\/\">Jornal de Not\u00edcias<\/a> de 15 de dezembro com dados estat\u00edsticos do IAC.<\/p><h5>Rita Pereira realiza sonhos de crian\u00e7as em tarde inesquec\u00edvel: \u00abIsto para mim \u00e9 que \u00e9 Natal\u00bb<\/h5><p>Rita Pereira levou amor, aten\u00e7\u00e3o, sorrisos e presentes \u00e0s crian\u00e7as do Instituto de Apoio \u00e0 Crian\u00e7a. Not\u00edcia da revista Maria de 18 de dezembro.<\/p><p>Link da not\u00edcia, reportagem e v\u00eddeo: <a href=\"http:\/\/bit.do\/fnHLj\">http:\/\/bit.do\/fnHLj<\/a><\/p><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1322\" aria-expanded=\"false\">November<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1322\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1322\" tabindex=\"0\" hidden=\"hidden\"><h5>Ado\u00e7\u00e3o deve ser prioridade<\/h5><p>Participa\u00e7\u00e3o de Matilde Sirgado do IAC, no programa &#8220;Fala Portugal&#8221; TV Record &#8211; dia 8 de novembro sobre o beb\u00e9 encontrado pelo sem-abrigo.<\/p><p>Link do v\u00eddeo: <a href=\"http:\/\/bit.do\/fkXk2\">http:\/\/bit.do\/fkXk2<\/a><\/p><h5>Beb\u00e9 encontrado pelo sem-abrigo<\/h5><p>Entrevista de Dulce Rocha Presidente do IAC \u00e0 TVI24 sobre o beb\u00e9 encontrado pelo sem-abrigo, 8 de novembro.<\/p><p>Link do v\u00eddeo: <a href=\"http:\/\/bit.do\/fiKC7\">http:\/\/bit.do\/fiKC7<\/a><\/p><h5>Beb\u00e9 encontrado pelo sem-abrigo<\/h5><p>Declara\u00e7\u00f5es de Matilde Sirgado do IAC \u00e0 RTP3 no dia 8 de novembro sobre o beb\u00e9 encontrado pelo sem-abrigo.<\/p><p>Visualizar o v\u00eddeo no link, do minuto 05:58 at\u00e9 13:12: <a href=\"http:\/\/bit.do\/fjjUt\">http:\/\/bit.do\/fjjUt<\/a><\/p><h5>Crian\u00e7as de Rua. &#8220;Hoje s\u00e3o menos mas o perigo \u00e9 muito maior&#8221;<\/h5><p>Not\u00edcia do Expresso de 13 de novembro com declara\u00e7\u00f5es de Matilde Sirgado do IAC<\/p><p>Link da not\u00edcia: <a href=\"http:\/\/bit.do\/fiyRX\">http:\/\/bit.do\/fiyRX<\/a><\/p><h5>Aquela mulher tem um problema grav\u00edssimo e tem de certeza sofrido imenso<\/h5><p>Entrevista da Presidente Honor\u00e1ria do IAC, Manuela Eanes \u00e0 RTP sobre o beb\u00e9 encontrado pelo sem-abrigo, dia 13 de novembro.<\/p><p>Visualizar a entrevista no link: <a href=\"http:\/\/bit.do\/fi5Dp\">http:\/\/bit.do\/fi5Dp<\/a><\/p><h5>&#8220;A lei n\u00e3o pro\u00edbe que a crian\u00e7a v\u00e1 outra vez para a m\u00e3e que a tentou matar&#8221;<\/h5><p>Dulce Rocha Presidente do IAC \u00e0 Vis\u00e3o de 14 novembro<\/p><p>Link da not\u00edcia: <a href=\"http:\/\/bit.do\/fi5CW\">http:\/\/bit.do\/fi5CW<\/a><\/p><h5>Quase 3 mil crian\u00e7as v\u00edtimas de abuso sexual nos \u00faltimos tr\u00eas anos<\/h5><p>Not\u00edcia da LUSA com declara\u00e7\u00f5es de Manuel Coutinho Secret\u00e1rio\u2013Geral do IAC no dia 16 de novembro<\/p><p>Link da not\u00edcia: <a href=\"http:\/\/bit.do\/fiyUf\">http:\/\/bit.do\/fiyUf<\/a><\/p><h5>O IAC \u2013 Projecto Rua em not\u00edcia da RTP1 no \u00e2mbito do 30\u00ba Anivers\u00e1rio da Conven\u00e7\u00e3o sobre os Direitos da Crian\u00e7a<\/h5><p>Dia 18 de novembro.<\/p><p>Visualizar a reportagem no link: <a href=\"http:\/\/bit.do\/fhLPS\">http:\/\/bit.do\/fhLPS<\/a><\/p><h5>Beb\u00e9 encontrado pelo sem-abrigo<\/h5><p>Presen\u00e7a de Dulce Rocha Presidente do IAC na TVI &#8211; &#8220;A Tarde \u00e9 Sua&#8221; sobre o beb\u00e9 encontrado pelo sem-abrigo, no dia 19 de novembro.<\/p><p>Link do v\u00eddeo: <a href=\"http:\/\/bit.do\/fiKE9\">http:\/\/bit.do\/fiKE9<\/a><\/p><h5>Trinta anos depois, ainda falta fazer \u201ccumprir\u201d a Conven\u00e7\u00e3o dos Direitos da Crian\u00e7a<\/h5><p>Not\u00edcia do P\u00fablico com declara\u00e7\u00f5es de Dulce Rocha Presidente do IAC no dia 20 de novembro.<\/p><p>Link da not\u00edcia: <a href=\"http:\/\/bit.do\/fiztR\">http:\/\/bit.do\/fiztR<\/a><\/p><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9dc18e7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9dc18e7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0882cef\" data-id=\"0882cef\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1d1854b elementor-widget elementor-widget-spacer\" data-id=\"1d1854b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>View IAC participation on the Media. Instituto de Apoio \u00e0 Crian\u00e7a, since 1983 defending and promoting children&#8217;s rights.<\/p>\n","protected":false},"author":2,"featured_media":9815,"parent":11997,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-11691","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Media | Instituto de Apoio \u00e0 Crian\u00e7a<\/title>\n<meta name=\"description\" content=\"View IAC participation on the Media. Instituto de Apoio \u00e0 Crian\u00e7a, since 1983 defending and promoting children&#039;s rights.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/iacrianca.pt\/en\/news\/iac-on-media\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Media | Instituto de Apoio \u00e0 Crian\u00e7a\" \/>\n<meta property=\"og:description\" content=\"View IAC participation on the Media. Instituto de Apoio \u00e0 Crian\u00e7a, since 1983 defending and promoting children&#039;s rights.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/iacrianca.pt\/en\/news\/iac-on-media\/\" \/>\n<meta property=\"og:site_name\" content=\"Instituto de Apoio \u00e0 Crian\u00e7a\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/iacinstitutodeapoioacrianca\" \/>\n<meta property=\"article:modified_time\" content=\"2022-02-24T10:26:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/iacrianca.pt\/wp-content\/uploads\/2020\/04\/inauguracao-nova-sede-iac-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1403\" \/>\n\t<meta property=\"og:image:height\" content=\"692\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@iacapoiocrianca\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"25 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/iacrianca.pt\\\/en\\\/news\\\/iac-on-media\\\/\",\"url\":\"https:\\\/\\\/iacrianca.pt\\\/en\\\/news\\\/iac-on-media\\\/\",\"name\":\"Media | Instituto de Apoio \u00e0 Crian\u00e7a\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/iacrianca.pt\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/iacrianca.pt\\\/en\\\/news\\\/iac-on-media\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/iacrianca.pt\\\/en\\\/news\\\/iac-on-media\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/iacrianca.pt\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/inauguracao-nova-sede-iac-3.jpg\",\"datePublished\":\"2020-07-13T10:46:47+00:00\",\"dateModified\":\"2022-02-24T10:26:50+00:00\",\"description\":\"View IAC participation on the Media. Instituto de Apoio \u00e0 Crian\u00e7a, since 1983 defending and promoting children's rights.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/iacrianca.pt\\\/en\\\/news\\\/iac-on-media\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/iacrianca.pt\\\/en\\\/news\\\/iac-on-media\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/iacrianca.pt\\\/en\\\/news\\\/iac-on-media\\\/#primaryimage\",\"url\":\"https:\\\/\\\/iacrianca.pt\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/inauguracao-nova-sede-iac-3.jpg\",\"contentUrl\":\"https:\\\/\\\/iacrianca.pt\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/inauguracao-nova-sede-iac-3.jpg\",\"width\":1403,\"height\":692,\"caption\":\"Inaugura\u00e7\u00e3o da Nova Sede IAC\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/iacrianca.pt\\\/en\\\/news\\\/iac-on-media\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/iacrianca.pt\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\\\/\\\/iacrianca.pt\\\/en\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"IAC on Media\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/iacrianca.pt\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/iacrianca.pt\\\/en\\\/\",\"name\":\"Instituto de Apoio \u00e0 Crian\u00e7a\",\"description\":\"Desde 1983 na defesa e promo\u00e7\u00e3o dos direitos da crian\u00e7a\",\"publisher\":{\"@id\":\"https:\\\/\\\/iacrianca.pt\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/iacrianca.pt\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/iacrianca.pt\\\/en\\\/#organization\",\"name\":\"Instituto de Apoio \u00e0 Crian\u00e7a\",\"url\":\"https:\\\/\\\/iacrianca.pt\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/iacrianca.pt\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/iacrianca.pt\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-iac-SD.jpg\",\"contentUrl\":\"https:\\\/\\\/iacrianca.pt\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-iac-SD.jpg\",\"width\":152,\"height\":73,\"caption\":\"Instituto de Apoio \u00e0 Crian\u00e7a\"},\"image\":{\"@id\":\"https:\\\/\\\/iacrianca.pt\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/iacinstitutodeapoioacrianca\",\"https:\\\/\\\/x.com\\\/iacapoiocrianca\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC0jjfZ_xkN_59gJf_RQ-ZnQ\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/instituto-de-apoio--criana\\\/\",\"https:\\\/\\\/www.instagram.com\\\/iacinstitutodeapoioacrianca\\\/\",\"https:\\\/\\\/criancasatortoeadireitos.wordpress.com\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Media | Instituto de Apoio \u00e0 Crian\u00e7a","description":"View IAC participation on the Media. Instituto de Apoio \u00e0 Crian\u00e7a, since 1983 defending and promoting children's rights.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/iacrianca.pt\/en\/news\/iac-on-media\/","og_locale":"en_US","og_type":"article","og_title":"Media | Instituto de Apoio \u00e0 Crian\u00e7a","og_description":"View IAC participation on the Media. Instituto de Apoio \u00e0 Crian\u00e7a, since 1983 defending and promoting children's rights.","og_url":"https:\/\/iacrianca.pt\/en\/news\/iac-on-media\/","og_site_name":"Instituto de Apoio \u00e0 Crian\u00e7a","article_publisher":"https:\/\/www.facebook.com\/iacinstitutodeapoioacrianca","article_modified_time":"2022-02-24T10:26:50+00:00","og_image":[{"width":1403,"height":692,"url":"https:\/\/iacrianca.pt\/wp-content\/uploads\/2020\/04\/inauguracao-nova-sede-iac-3.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@iacapoiocrianca","twitter_misc":{"Est. reading time":"25 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/iacrianca.pt\/en\/news\/iac-on-media\/","url":"https:\/\/iacrianca.pt\/en\/news\/iac-on-media\/","name":"Media | Instituto de Apoio \u00e0 Crian\u00e7a","isPartOf":{"@id":"https:\/\/iacrianca.pt\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/iacrianca.pt\/en\/news\/iac-on-media\/#primaryimage"},"image":{"@id":"https:\/\/iacrianca.pt\/en\/news\/iac-on-media\/#primaryimage"},"thumbnailUrl":"https:\/\/iacrianca.pt\/wp-content\/uploads\/2020\/04\/inauguracao-nova-sede-iac-3.jpg","datePublished":"2020-07-13T10:46:47+00:00","dateModified":"2022-02-24T10:26:50+00:00","description":"View IAC participation on the Media. Instituto de Apoio \u00e0 Crian\u00e7a, since 1983 defending and promoting children's rights.","breadcrumb":{"@id":"https:\/\/iacrianca.pt\/en\/news\/iac-on-media\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/iacrianca.pt\/en\/news\/iac-on-media\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/iacrianca.pt\/en\/news\/iac-on-media\/#primaryimage","url":"https:\/\/iacrianca.pt\/wp-content\/uploads\/2020\/04\/inauguracao-nova-sede-iac-3.jpg","contentUrl":"https:\/\/iacrianca.pt\/wp-content\/uploads\/2020\/04\/inauguracao-nova-sede-iac-3.jpg","width":1403,"height":692,"caption":"Inaugura\u00e7\u00e3o da Nova Sede IAC"},{"@type":"BreadcrumbList","@id":"https:\/\/iacrianca.pt\/en\/news\/iac-on-media\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/iacrianca.pt\/en\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/iacrianca.pt\/en\/news\/"},{"@type":"ListItem","position":3,"name":"IAC on Media"}]},{"@type":"WebSite","@id":"https:\/\/iacrianca.pt\/en\/#website","url":"https:\/\/iacrianca.pt\/en\/","name":"Instituto de Apoio \u00e0 Crian\u00e7a","description":"Desde 1983 na defesa e promo\u00e7\u00e3o dos direitos da crian\u00e7a","publisher":{"@id":"https:\/\/iacrianca.pt\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/iacrianca.pt\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/iacrianca.pt\/en\/#organization","name":"Instituto de Apoio \u00e0 Crian\u00e7a","url":"https:\/\/iacrianca.pt\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/iacrianca.pt\/en\/#\/schema\/logo\/image\/","url":"https:\/\/iacrianca.pt\/wp-content\/uploads\/2020\/04\/logo-iac-SD.jpg","contentUrl":"https:\/\/iacrianca.pt\/wp-content\/uploads\/2020\/04\/logo-iac-SD.jpg","width":152,"height":73,"caption":"Instituto de Apoio \u00e0 Crian\u00e7a"},"image":{"@id":"https:\/\/iacrianca.pt\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/iacinstitutodeapoioacrianca","https:\/\/x.com\/iacapoiocrianca","https:\/\/www.youtube.com\/channel\/UC0jjfZ_xkN_59gJf_RQ-ZnQ","https:\/\/www.linkedin.com\/company\/instituto-de-apoio--criana\/","https:\/\/www.instagram.com\/iacinstitutodeapoioacrianca\/","https:\/\/criancasatortoeadireitos.wordpress.com\/"]}]}},"_links":{"self":[{"href":"https:\/\/iacrianca.pt\/en\/wp-json\/wp\/v2\/pages\/11691","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iacrianca.pt\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/iacrianca.pt\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/iacrianca.pt\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/iacrianca.pt\/en\/wp-json\/wp\/v2\/comments?post=11691"}],"version-history":[{"count":0,"href":"https:\/\/iacrianca.pt\/en\/wp-json\/wp\/v2\/pages\/11691\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/iacrianca.pt\/en\/wp-json\/wp\/v2\/pages\/11997"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/iacrianca.pt\/en\/wp-json\/wp\/v2\/media\/9815"}],"wp:attachment":[{"href":"https:\/\/iacrianca.pt\/en\/wp-json\/wp\/v2\/media?parent=11691"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}