{"id":16358,"date":"2022-11-03T12:13:33","date_gmt":"2022-11-03T12:13:33","guid":{"rendered":"https:\/\/iacrianca.pt\/?p=16358"},"modified":"2022-11-08T17:09:12","modified_gmt":"2022-11-08T17:09:12","slug":"jornadas-da-educacao-em-moscavide-e-o-superior-interesse-da-crianca","status":"publish","type":"post","link":"https:\/\/iacrianca.pt\/en\/2022\/11\/jornadas-da-educacao-em-moscavide-e-o-superior-interesse-da-crianca\/","title":{"rendered":"Jornadas da Educa\u00e7\u00e3o em Moscavide e o Superior interesse da Crian\u00e7a"},"content":{"rendered":"<p><span data-contrast=\"auto\">O Setor da Humaniza\u00e7\u00e3o dos Servi\u00e7os de Atendimento \u00e0 Crian\u00e7a, na pessoa da sua Coordenadora Melanie Tavares, esteve em representa\u00e7\u00e3o do IAC a participar nas <a href=\"https:\/\/jornadasdaeducacao.jf-moscavideportela.pt\/\">Jornadas na Educa\u00e7\u00e3o 2022: \u201cEscola: (re)volu\u00e7\u00e3o, emo\u00e7\u00e3o, rela\u00e7\u00e3o e participa\u00e7\u00e3o\u201d<\/a> promovidas pela Junta de Freguesia de Moscavide, no passado dia 21 de outubro.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Particip\u00e1mos no painel\u00a0 &#8220;Novos desafios dos profissionais, um olhar para dentro com a comunica\u00e7\u00e3o \u201cO superior interesse da Crian\u00e7a \u201c.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Foi uma experi\u00eancia muito enriquecedora pela excel\u00eancia de oradores, de que destaco a presen\u00e7a (com uma comunica\u00e7\u00e3o on-line) do Prof. Jos\u00e9 Pacheco.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Estiveram presentes cerca de 100 profissionais de educa\u00e7\u00e3o e da \u00e1rea social que foram bastante participativos e partilharam as suas experi\u00eancias.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Setor da Humaniza\u00e7\u00e3o dos Servi\u00e7os de Atendimento \u00e0 Crian\u00e7a, na pessoa da sua Coordenadora Melanie Tavares, esteve em representa\u00e7\u00e3o do IAC a participar nas Jornadas na Educa\u00e7\u00e3o 2022: \u201cEscola: (re)volu\u00e7\u00e3o, emo\u00e7\u00e3o, rela\u00e7\u00e3o e participa\u00e7\u00e3o\u201d promovidas pela Junta de Freguesia de Moscavide, no passado dia 21 de outubro.\u00a0 Particip\u00e1mos no painel\u00a0 &#8220;Novos desafios dos profissionais,&hellip;<\/p>\n","protected":false},"author":2,"featured_media":16359,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[63],"tags":[],"class_list":["post-16358","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-newsletter","category-63","description-off"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Jornadas da Educa\u00e7\u00e3o em Moscavide e o Superior interesse da Crian\u00e7a | Instituto de Apoio \u00e0 Crian\u00e7a<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/iacrianca.pt\/en\/2022\/11\/jornadas-da-educacao-em-moscavide-e-o-superior-interesse-da-crianca\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jornadas da Educa\u00e7\u00e3o em Moscavide e o Superior interesse da Crian\u00e7a | Instituto de Apoio \u00e0 Crian\u00e7a\" \/>\n<meta property=\"og:description\" content=\"O Setor da Humaniza\u00e7\u00e3o dos Servi\u00e7os de Atendimento \u00e0 Crian\u00e7a, na pessoa da sua Coordenadora Melanie Tavares, esteve em representa\u00e7\u00e3o do IAC a participar nas Jornadas na Educa\u00e7\u00e3o 2022: \u201cEscola: (re)volu\u00e7\u00e3o, emo\u00e7\u00e3o, rela\u00e7\u00e3o e participa\u00e7\u00e3o\u201d promovidas pela Junta de Freguesia de Moscavide, no passado dia 21 de outubro.\u00a0 Particip\u00e1mos no painel\u00a0 &#8220;Novos desafios dos profissionais,&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/iacrianca.pt\/en\/2022\/11\/jornadas-da-educacao-em-moscavide-e-o-superior-interesse-da-crianca\/\" \/>\n<meta property=\"og:site_name\" content=\"Instituto de Apoio \u00e0 Crian\u00e7a\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/iacinstitutodeapoioacrianca\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-03T12:13:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-08T17:09:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/iacrianca.pt\/wp-content\/uploads\/jornadas.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"817\" \/>\n\t<meta property=\"og:image:height\" content=\"613\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Administra\u00e7\u00e3o IAC\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@iacapoiocrianca\" \/>\n<meta name=\"twitter:site\" content=\"@iacapoiocrianca\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Administra\u00e7\u00e3o IAC\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/iacrianca.pt\\\/en\\\/2022\\\/11\\\/jornadas-da-educacao-em-moscavide-e-o-superior-interesse-da-crianca\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/iacrianca.pt\\\/en\\\/2022\\\/11\\\/jornadas-da-educacao-em-moscavide-e-o-superior-interesse-da-crianca\\\/\"},\"author\":{\"name\":\"Administra\u00e7\u00e3o IAC\",\"@id\":\"https:\\\/\\\/iacrianca.pt\\\/en\\\/#\\\/schema\\\/person\\\/1c48c6e4b70d0dc7360e4b28ceaa5f6b\"},\"headline\":\"Jornadas da Educa\u00e7\u00e3o em Moscavide e o Superior interesse da Crian\u00e7a\",\"datePublished\":\"2022-11-03T12:13:33+00:00\",\"dateModified\":\"2022-11-08T17:09:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/iacrianca.pt\\\/en\\\/2022\\\/11\\\/jornadas-da-educacao-em-moscavide-e-o-superior-interesse-da-crianca\\\/\"},\"wordCount\":138,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/iacrianca.pt\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/iacrianca.pt\\\/en\\\/2022\\\/11\\\/jornadas-da-educacao-em-moscavide-e-o-superior-interesse-da-crianca\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/iacrianca.pt\\\/wp-content\\\/uploads\\\/jornadas.jpg\",\"articleSection\":[\"Newsletter\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/iacrianca.pt\\\/en\\\/2022\\\/11\\\/jornadas-da-educacao-em-moscavide-e-o-superior-interesse-da-crianca\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/iacrianca.pt\\\/en\\\/2022\\\/11\\\/jornadas-da-educacao-em-moscavide-e-o-superior-interesse-da-crianca\\\/\",\"url\":\"https:\\\/\\\/iacrianca.pt\\\/en\\\/2022\\\/11\\\/jornadas-da-educacao-em-moscavide-e-o-superior-interesse-da-crianca\\\/\",\"name\":\"Jornadas da Educa\u00e7\u00e3o em Moscavide e o Superior interesse da Crian\u00e7a | Instituto de Apoio \u00e0 Crian\u00e7a\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/iacrianca.pt\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/iacrianca.pt\\\/en\\\/2022\\\/11\\\/jornadas-da-educacao-em-moscavide-e-o-superior-interesse-da-crianca\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/iacrianca.pt\\\/en\\\/2022\\\/11\\\/jornadas-da-educacao-em-moscavide-e-o-superior-interesse-da-crianca\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/iacrianca.pt\\\/wp-content\\\/uploads\\\/jornadas.jpg\",\"datePublished\":\"2022-11-03T12:13:33+00:00\",\"dateModified\":\"2022-11-08T17:09:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/iacrianca.pt\\\/en\\\/2022\\\/11\\\/jornadas-da-educacao-em-moscavide-e-o-superior-interesse-da-crianca\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/iacrianca.pt\\\/en\\\/2022\\\/11\\\/jornadas-da-educacao-em-moscavide-e-o-superior-interesse-da-crianca\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/iacrianca.pt\\\/en\\\/2022\\\/11\\\/jornadas-da-educacao-em-moscavide-e-o-superior-interesse-da-crianca\\\/#primaryimage\",\"url\":\"https:\\\/\\\/iacrianca.pt\\\/wp-content\\\/uploads\\\/jornadas.jpg\",\"contentUrl\":\"https:\\\/\\\/iacrianca.pt\\\/wp-content\\\/uploads\\\/jornadas.jpg\",\"width\":817,\"height\":613},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/iacrianca.pt\\\/en\\\/2022\\\/11\\\/jornadas-da-educacao-em-moscavide-e-o-superior-interesse-da-crianca\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/iacrianca.pt\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jornadas da Educa\u00e7\u00e3o em Moscavide e o Superior interesse da Crian\u00e7a\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/iacrianca.pt\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/iacrianca.pt\\\/en\\\/\",\"name\":\"Instituto de Apoio \u00e0 Crian\u00e7a\",\"description\":\"Desde 1983 na defesa e promo\u00e7\u00e3o dos direitos da crian\u00e7a\",\"publisher\":{\"@id\":\"https:\\\/\\\/iacrianca.pt\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/iacrianca.pt\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/iacrianca.pt\\\/en\\\/#organization\",\"name\":\"Instituto de Apoio \u00e0 Crian\u00e7a\",\"url\":\"https:\\\/\\\/iacrianca.pt\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/iacrianca.pt\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/iacrianca.pt\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-iac-SD.jpg\",\"contentUrl\":\"https:\\\/\\\/iacrianca.pt\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-iac-SD.jpg\",\"width\":152,\"height\":73,\"caption\":\"Instituto de Apoio \u00e0 Crian\u00e7a\"},\"image\":{\"@id\":\"https:\\\/\\\/iacrianca.pt\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/iacinstitutodeapoioacrianca\",\"https:\\\/\\\/x.com\\\/iacapoiocrianca\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC0jjfZ_xkN_59gJf_RQ-ZnQ\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/instituto-de-apoio--criana\\\/\",\"https:\\\/\\\/www.instagram.com\\\/iacinstitutodeapoioacrianca\\\/\",\"https:\\\/\\\/criancasatortoeadireitos.wordpress.com\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/iacrianca.pt\\\/en\\\/#\\\/schema\\\/person\\\/1c48c6e4b70d0dc7360e4b28ceaa5f6b\",\"name\":\"Administra\u00e7\u00e3o IAC\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/60b998c71de37dcc1398fc6d48c6b5ed7533e3ceec837c948055f072e3158ff1?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/60b998c71de37dcc1398fc6d48c6b5ed7533e3ceec837c948055f072e3158ff1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/60b998c71de37dcc1398fc6d48c6b5ed7533e3ceec837c948055f072e3158ff1?s=96&d=mm&r=g\",\"caption\":\"Administra\u00e7\u00e3o IAC\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jornadas da Educa\u00e7\u00e3o em Moscavide e o Superior interesse da Crian\u00e7a | Instituto de Apoio \u00e0 Crian\u00e7a","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/iacrianca.pt\/en\/2022\/11\/jornadas-da-educacao-em-moscavide-e-o-superior-interesse-da-crianca\/","og_locale":"en_US","og_type":"article","og_title":"Jornadas da Educa\u00e7\u00e3o em Moscavide e o Superior interesse da Crian\u00e7a | Instituto de Apoio \u00e0 Crian\u00e7a","og_description":"O Setor da Humaniza\u00e7\u00e3o dos Servi\u00e7os de Atendimento \u00e0 Crian\u00e7a, na pessoa da sua Coordenadora Melanie Tavares, esteve em representa\u00e7\u00e3o do IAC a participar nas Jornadas na Educa\u00e7\u00e3o 2022: \u201cEscola: (re)volu\u00e7\u00e3o, emo\u00e7\u00e3o, rela\u00e7\u00e3o e participa\u00e7\u00e3o\u201d promovidas pela Junta de Freguesia de Moscavide, no passado dia 21 de outubro.\u00a0 Particip\u00e1mos no painel\u00a0 &#8220;Novos desafios dos profissionais,&hellip;","og_url":"https:\/\/iacrianca.pt\/en\/2022\/11\/jornadas-da-educacao-em-moscavide-e-o-superior-interesse-da-crianca\/","og_site_name":"Instituto de Apoio \u00e0 Crian\u00e7a","article_publisher":"https:\/\/www.facebook.com\/iacinstitutodeapoioacrianca","article_published_time":"2022-11-03T12:13:33+00:00","article_modified_time":"2022-11-08T17:09:12+00:00","og_image":[{"width":817,"height":613,"url":"https:\/\/iacrianca.pt\/wp-content\/uploads\/jornadas.jpg","type":"image\/jpeg"}],"author":"Administra\u00e7\u00e3o IAC","twitter_card":"summary_large_image","twitter_creator":"@iacapoiocrianca","twitter_site":"@iacapoiocrianca","twitter_misc":{"Written by":"Administra\u00e7\u00e3o IAC","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/iacrianca.pt\/en\/2022\/11\/jornadas-da-educacao-em-moscavide-e-o-superior-interesse-da-crianca\/#article","isPartOf":{"@id":"https:\/\/iacrianca.pt\/en\/2022\/11\/jornadas-da-educacao-em-moscavide-e-o-superior-interesse-da-crianca\/"},"author":{"name":"Administra\u00e7\u00e3o IAC","@id":"https:\/\/iacrianca.pt\/en\/#\/schema\/person\/1c48c6e4b70d0dc7360e4b28ceaa5f6b"},"headline":"Jornadas da Educa\u00e7\u00e3o em Moscavide e o Superior interesse da Crian\u00e7a","datePublished":"2022-11-03T12:13:33+00:00","dateModified":"2022-11-08T17:09:12+00:00","mainEntityOfPage":{"@id":"https:\/\/iacrianca.pt\/en\/2022\/11\/jornadas-da-educacao-em-moscavide-e-o-superior-interesse-da-crianca\/"},"wordCount":138,"commentCount":0,"publisher":{"@id":"https:\/\/iacrianca.pt\/en\/#organization"},"image":{"@id":"https:\/\/iacrianca.pt\/en\/2022\/11\/jornadas-da-educacao-em-moscavide-e-o-superior-interesse-da-crianca\/#primaryimage"},"thumbnailUrl":"https:\/\/iacrianca.pt\/wp-content\/uploads\/jornadas.jpg","articleSection":["Newsletter"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/iacrianca.pt\/en\/2022\/11\/jornadas-da-educacao-em-moscavide-e-o-superior-interesse-da-crianca\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/iacrianca.pt\/en\/2022\/11\/jornadas-da-educacao-em-moscavide-e-o-superior-interesse-da-crianca\/","url":"https:\/\/iacrianca.pt\/en\/2022\/11\/jornadas-da-educacao-em-moscavide-e-o-superior-interesse-da-crianca\/","name":"Jornadas da Educa\u00e7\u00e3o em Moscavide e o Superior interesse da Crian\u00e7a | Instituto de Apoio \u00e0 Crian\u00e7a","isPartOf":{"@id":"https:\/\/iacrianca.pt\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/iacrianca.pt\/en\/2022\/11\/jornadas-da-educacao-em-moscavide-e-o-superior-interesse-da-crianca\/#primaryimage"},"image":{"@id":"https:\/\/iacrianca.pt\/en\/2022\/11\/jornadas-da-educacao-em-moscavide-e-o-superior-interesse-da-crianca\/#primaryimage"},"thumbnailUrl":"https:\/\/iacrianca.pt\/wp-content\/uploads\/jornadas.jpg","datePublished":"2022-11-03T12:13:33+00:00","dateModified":"2022-11-08T17:09:12+00:00","breadcrumb":{"@id":"https:\/\/iacrianca.pt\/en\/2022\/11\/jornadas-da-educacao-em-moscavide-e-o-superior-interesse-da-crianca\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/iacrianca.pt\/en\/2022\/11\/jornadas-da-educacao-em-moscavide-e-o-superior-interesse-da-crianca\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/iacrianca.pt\/en\/2022\/11\/jornadas-da-educacao-em-moscavide-e-o-superior-interesse-da-crianca\/#primaryimage","url":"https:\/\/iacrianca.pt\/wp-content\/uploads\/jornadas.jpg","contentUrl":"https:\/\/iacrianca.pt\/wp-content\/uploads\/jornadas.jpg","width":817,"height":613},{"@type":"BreadcrumbList","@id":"https:\/\/iacrianca.pt\/en\/2022\/11\/jornadas-da-educacao-em-moscavide-e-o-superior-interesse-da-crianca\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/iacrianca.pt\/en\/"},{"@type":"ListItem","position":2,"name":"Jornadas da Educa\u00e7\u00e3o em Moscavide e o Superior interesse da Crian\u00e7a"}]},{"@type":"WebSite","@id":"https:\/\/iacrianca.pt\/en\/#website","url":"https:\/\/iacrianca.pt\/en\/","name":"Instituto de Apoio \u00e0 Crian\u00e7a","description":"Desde 1983 na defesa e promo\u00e7\u00e3o dos direitos da crian\u00e7a","publisher":{"@id":"https:\/\/iacrianca.pt\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/iacrianca.pt\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/iacrianca.pt\/en\/#organization","name":"Instituto de Apoio \u00e0 Crian\u00e7a","url":"https:\/\/iacrianca.pt\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/iacrianca.pt\/en\/#\/schema\/logo\/image\/","url":"https:\/\/iacrianca.pt\/wp-content\/uploads\/2020\/04\/logo-iac-SD.jpg","contentUrl":"https:\/\/iacrianca.pt\/wp-content\/uploads\/2020\/04\/logo-iac-SD.jpg","width":152,"height":73,"caption":"Instituto de Apoio \u00e0 Crian\u00e7a"},"image":{"@id":"https:\/\/iacrianca.pt\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/iacinstitutodeapoioacrianca","https:\/\/x.com\/iacapoiocrianca","https:\/\/www.youtube.com\/channel\/UC0jjfZ_xkN_59gJf_RQ-ZnQ","https:\/\/www.linkedin.com\/company\/instituto-de-apoio--criana\/","https:\/\/www.instagram.com\/iacinstitutodeapoioacrianca\/","https:\/\/criancasatortoeadireitos.wordpress.com\/"]},{"@type":"Person","@id":"https:\/\/iacrianca.pt\/en\/#\/schema\/person\/1c48c6e4b70d0dc7360e4b28ceaa5f6b","name":"Administra\u00e7\u00e3o IAC","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/60b998c71de37dcc1398fc6d48c6b5ed7533e3ceec837c948055f072e3158ff1?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/60b998c71de37dcc1398fc6d48c6b5ed7533e3ceec837c948055f072e3158ff1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/60b998c71de37dcc1398fc6d48c6b5ed7533e3ceec837c948055f072e3158ff1?s=96&d=mm&r=g","caption":"Administra\u00e7\u00e3o IAC"}}]}},"_links":{"self":[{"href":"https:\/\/iacrianca.pt\/en\/wp-json\/wp\/v2\/posts\/16358","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iacrianca.pt\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/iacrianca.pt\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/iacrianca.pt\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/iacrianca.pt\/en\/wp-json\/wp\/v2\/comments?post=16358"}],"version-history":[{"count":0,"href":"https:\/\/iacrianca.pt\/en\/wp-json\/wp\/v2\/posts\/16358\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/iacrianca.pt\/en\/wp-json\/wp\/v2\/media\/16359"}],"wp:attachment":[{"href":"https:\/\/iacrianca.pt\/en\/wp-json\/wp\/v2\/media?parent=16358"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/iacrianca.pt\/en\/wp-json\/wp\/v2\/categories?post=16358"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/iacrianca.pt\/en\/wp-json\/wp\/v2\/tags?post=16358"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}